{"id":9956,"date":"2023-06-29T09:24:15","date_gmt":"2023-06-29T02:24:15","guid":{"rendered":"https:\/\/mimaki-inksub.com\/en\/?post_type=product&#038;p=9956"},"modified":"2023-07-10T09:23:50","modified_gmt":"2023-07-10T02:23:50","slug":"printer-a3020","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020"},"content":{"rendered":"<h1><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_Arena_A3020_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 : 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-9978 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020\" width=\"1900\" height=\"500\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020.jpg 1900w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-300x79.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1024x269.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-768x202.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1536x404.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-600x158.jpg 600w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >\u0e2a\u0e32\u0e23\u0e1a\u0e31\u0e0d<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a049c7ef2981\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a049c7ef2981\"  type=\"checkbox\" id=\"item-6a049c7ef2981\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_Arena_A3020_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 : 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 : 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><ul class='ez-toc-list-level-2'><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%AA%E0%B8%B3%E0%B8%84%E0%B8%B1%E0%B8%8D%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%B4%E0%B9%80%E0%B8%A8%E0%B8%A9%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%AA%E0%B8%A1%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B9%82%E0%B8%A2%E0%B8%8A%E0%B8%99%E0%B9%8C%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%A0%E0%B8%B2%E0%B8%9E%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%94%E0%B8%B5\" title=\"\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\">\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B9%80%E0%B8%A3%E0%B9%87%E0%B8%A7%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%97%E0%B8%B3%E0%B8%87%E0%B8%B2%E0%B8%99\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%AB%E0%B8%A5%E0%B8%B2%E0%B8%81%E0%B8%AB%E0%B8%A5%E0%B8%B2%E0%B8%A2%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%A2%E0%B8%B7%E0%B8%94%E0%B8%AB%E0%B8%A2%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%83%E0%B8%8A%E0%B9%89%E0%B8%87%E0%B8%B2%E0%B8%99\" title=\"\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\">\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%94%E0%B8%B9%E0%B9%81%E0%B8%A5%E0%B8%A3%E0%B8%B1%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%9A%E0%B8%B3%E0%B8%A3%E0%B8%B8%E0%B8%87%E0%B8%A3%E0%B8%B1%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#%E0%B8%AA%E0%B8%A3%E0%B8%B8%E0%B8%9B\" title=\"\u0e2a\u0e23\u0e38\u0e1b\">\u0e2a\u0e23\u0e38\u0e1b<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#FAQs_%E0%B8%84%E0%B8%B3%E0%B8%96%E0%B8%B2%E0%B8%A1%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%9E%E0%B8%9A%E0%B8%9A%E0%B9%88%E0%B8%AD%E0%B8%A2\" title=\"FAQs (\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22)\">FAQs (\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22)<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%AA%E0%B8%B3%E0%B8%84%E0%B8%B1%E0%B8%8D%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e04\u0e25\u0e38\u0e21\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01<strong><span><a onclick=\"read_toggle(1901689035, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1901689035\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1901689035\" style=\"display: none;\"><\/strong> \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020 \u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01 \u0e01\u0e27\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2b\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<strong><\/div><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%B4%E0%B9%80%E0%B8%A8%E0%B8%A9%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e31\u0e1a 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e35\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e2a\u0e35\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 <strong><span><a onclick=\"read_toggle(776243429, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink776243429\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read776243429\" style=\"display: none;\"><\/strong>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e44\u0e14\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e40\u0e27\u0e25 \u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e1e \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<strong><\/div><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%AA%E0%B8%A1%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B9%82%E0%B8%A2%E0%B8%8A%E0%B8%99%E0%B9%8C%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%A0%E0%B8%B2%E0%B8%9E%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%94%E0%B8%B5\"><\/span>\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 <a href=\"https:\/\/virgo-sport.com\/shop\/virgo-sport\/TH-home.html\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a> \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e41\u0e25\u0e30 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B9%80%E0%B8%A3%E0%B9%87%E0%B8%A7%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%97%E0%B8%B3%E0%B8%87%E0%B8%B2%E0%B8%99\"><\/span>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e44\u0e14\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e25\u0e14\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%AB%E0%B8%A5%E0%B8%B2%E0%B8%81%E0%B8%AB%E0%B8%A5%E0%B8%B2%E0%B8%A2%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e04\u0e23\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%A2%E0%B8%B7%E0%B8%94%E0%B8%AB%E0%B8%A2%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%83%E0%B8%8A%E0%B9%89%E0%B8%87%E0%B8%B2%E0%B8%99\"><\/span>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27 \u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%94%E0%B8%B9%E0%B9%81%E0%B8%A5%E0%B8%A3%E0%B8%B1%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%9A%E0%B8%B3%E0%B8%A3%E0%B8%B8%E0%B8%87%E0%B8%A3%E0%B8%B1%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%A1%E0%B8%B5_3_%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23 \u0e41\u0e25\u0e30 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n<ul>\n<li>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e23\u0e32 \u0e04\u0e27\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e40\u0e2a\u0e21\u0e2d<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08 \u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14 \u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/li>\n<li>\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%AA%E0%B8%A3%E0%B8%B8%E0%B8%9B\"><\/span>\u0e2a\u0e23\u0e38\u0e1b<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35 \u0e41\u0e25\u0e30 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 <strong><span><a onclick=\"read_toggle(1482406135, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1482406135\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1482406135\" style=\"display: none;\">\u00a0<\/strong>\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07 \u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13 \u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35 \u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e2d\u0e22\u0e48\u0e32\u0e23\u0e2d\u0e0a\u0e49\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d<a href=\"https:\/\/mimaki-inksub.com\/en\/product\/heatroller190cm\/\">\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/a>\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<strong><\/div><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"FAQs_%E0%B8%84%E0%B8%B3%E0%B8%96%E0%B8%B2%E0%B8%A1%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%9E%E0%B8%9A%E0%B8%9A%E0%B9%88%E0%B8%AD%E0%B8%A2\"><\/span>FAQs (\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>1. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e44\u0e2b\u0e21?<\/strong><\/p>\n<p>\u0e43\u0e0a\u0e48, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e43\u0e19\u0e04\u0e23\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p>\n<p><strong>2. \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/strong><\/p>\n<p>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e32\u0e08\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e23\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\n<p><strong>3. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e14\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07?<\/strong><\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29, \u0e1c\u0e49\u0e32, \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/p>\n<p><strong>4. \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e22\u0e32\u0e01\u0e44\u0e2b\u0e21?<\/strong><\/p>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e40\u0e25\u0e22 \u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e08\u0e30\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e25\u0e30\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33<\/p>\n<p><strong>5. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/strong><\/p>\n<p>\u0e43\u0e0a\u0e48, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e31\u0e01\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e08\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9952\" class=\"elementor elementor-9952\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6c9769e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c9769e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8c9340\" data-id=\"d8c9340\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a6a7c5 elementor-widget elementor-widget-heading\" data-id=\"9a6a7c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 : 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a24439 elementor-widget elementor-widget-image\" data-id=\"8a24439\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"269\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1024x269.jpg\" class=\"attachment-large size-large wp-image-9978 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1024x269.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-300x79.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-768x202.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1536x404.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-600x158.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020.jpg 1900w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/269;\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"269\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1024x269.jpg\" class=\"attachment-large size-large wp-image-9978\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1024x269.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-300x79.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-768x202.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1536x404.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-600x158.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020.jpg 1900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e325c9 elementor-widget elementor-widget-heading\" data-id=\"5e325c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fadbb3 elementor-widget elementor-widget-text-editor\" data-id=\"4fadbb3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e04\u0e25\u0e38\u0e21\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020 \u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2b\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524f608 elementor-widget elementor-widget-heading\" data-id=\"524f608\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1f3edd elementor-widget elementor-widget-text-editor\" data-id=\"f1f3edd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e31\u0e1a 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e2a\u0e35\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e44\u0e14\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e1e\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c50f91 elementor-widget elementor-widget-heading\" data-id=\"2c50f91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f343f4 elementor-widget elementor-widget-text-editor\" data-id=\"7f343f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c80cb53 elementor-widget elementor-widget-heading\" data-id=\"c80cb53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74d02f8 elementor-widget elementor-widget-text-editor\" data-id=\"74d02f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2282553 elementor-widget elementor-widget-heading\" data-id=\"2282553\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-462c122 elementor-widget elementor-widget-text-editor\" data-id=\"462c122\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e25\u0e14\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97a133e elementor-widget elementor-widget-heading\" data-id=\"97a133e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9a233 elementor-widget elementor-widget-text-editor\" data-id=\"4b9a233\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e04\u0e23\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a4de14 elementor-widget elementor-widget-heading\" data-id=\"7a4de14\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-147f304 elementor-widget elementor-widget-text-editor\" data-id=\"147f304\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6def3b elementor-widget elementor-widget-heading\" data-id=\"b6def3b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92d5926 elementor-widget elementor-widget-text-editor\" data-id=\"92d5926\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p><ul><li><p>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e23\u0e32 \u0e04\u0e27\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e40\u0e2a\u0e21\u0e2d<\/p><\/li><li><p>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/p><\/li><li><p>\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32\u0e2b\u0e21\u0e36\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b06e8f elementor-widget elementor-widget-heading\" data-id=\"5b06e8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e23\u0e38\u0e1b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c780f elementor-widget elementor-widget-text-editor\" data-id=\"b5c780f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p><p>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e2d\u0e22\u0e48\u0e32\u0e23\u0e2d\u0e0a\u0e49\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e25\u0e34\u0e07\u0e04\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e40\u0e25\u0e22!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f5f83 elementor-widget elementor-widget-heading\" data-id=\"f6f5f83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQs (\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6384b elementor-widget elementor-widget-text-editor\" data-id=\"1d6384b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>1. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e44\u0e2b\u0e21?<\/strong><\/p><p>\u0e43\u0e0a\u0e48, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e43\u0e19\u0e04\u0e23\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p><p><strong>2. \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/strong><\/p><p>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e32\u0e08\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e23\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<\/p><p><strong>3. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e14\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07?<\/strong><\/p><p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29, \u0e1c\u0e49\u0e32, \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/p><p><strong>4. \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e22\u0e32\u0e01\u0e44\u0e2b\u0e21?<\/strong><\/p><p>\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e40\u0e25\u0e22 \u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e08\u0e30\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e25\u0e30\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33<\/p><p><strong>5. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/strong><\/p><p>\u0e43\u0e0a\u0e48, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35 3 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e31\u0e01\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e08\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fa6a894 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fa6a894\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56c31fd\" data-id=\"56c31fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98cb3e6 elementor-widget elementor-widget-heading\" data-id=\"98cb3e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29<br>\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 0.89%<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 1 \u0e1b\u0e35<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b1e63c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b1e63c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f25837\" data-id=\"0f25837\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbc4bd elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ccbc4bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-14648ba\" data-id=\"14648ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb7230 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5cb7230\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dea3b32\" data-id=\"dea3b32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c8ee794 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"c8ee794\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6042d9\" data-id=\"d6042d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-40dec4b elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"40dec4b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-383e515\" data-id=\"383e515\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d3a686 elementor-widget elementor-widget-heading\" data-id=\"4d3a686\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e23\u0e35\u0e27\u0e34\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba98d59 elementor-hidden-mobile\" data-id=\"ba98d59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-24f449a\" data-id=\"24f449a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9595021 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"9595021\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca6124f\" data-id=\"ca6124f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c801412 elementor-widget elementor-widget-heading\" data-id=\"c801412\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec7105d elementor-hidden-mobile\" data-id=\"ec7105d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d6f5d94 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6f5d94\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fb34d96\" data-id=\"fb34d96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f07b00 elementor-widget elementor-widget-image\" data-id=\"2f07b00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020.png\" class=\"attachment-full size-full wp-image-9984 lazyload\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-100x100.png 100w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><noscript><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020.png\" class=\"attachment-full size-full wp-image-9984\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a4023a3020-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9592488\" data-id=\"9592488\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a933ba elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-calculated-fields-form\" data-id=\"6a933ba\" data-element_type=\"widget\" data-widget_type=\"calculated-fields-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>#fbuilder .cff-button-field{text-align:center;}\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"?\" method=\"post\" enctype=\"multipart\/form-data\" class=\"cff-form \"  dir=\"ltr\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/><pre style=\"display:none !important;\"><script type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname13\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fcurrency\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e32\\u0e04\\u0e32\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":false,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"currencySymbol\":\"\",\"currencyText\":\" \\u0e1a\\u0e32\\u0e17\",\"thousandSeparator\":\",\",\"centSeparator\":\".\",\"noCents\":true,\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":true,\"twoDecimals\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname18\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c %\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 30%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 35%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 40%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 45%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 50%\"],\"optgroup\":[false,false,false,false,false],\"choicesVal\":[\"0.30\",\"0.35\",\"0.40\",\"0.45\",\"0.50\"],\"choicesDep\":[[],[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname11\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e01\\u0e39\\u0e49\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"value\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 12 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 24 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 36 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"12 \",\"24 \",\"36 \"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname14\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fButton\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"sType\":\"calculate\",\"sValue\":\"\\u0e04\\u0e33\\u0e19\\u0e27\\u0e19\\u0e2a\\u0e34\\u0e19\\u0e40\\u0e0a\\u0e37\\u0e48\\u0e2d\",\"sOnclick\":\"\",\"sOnmousedown\":\"\",\"sLoading\":true,\"sMultipage\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname19\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname13*fieldname18)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname16\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"prec(fieldname13-fieldname19)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fnumber\",\"userhelp\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 0.89% \\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 %\",\"predefined\":\"0.89%\",\"predefinedClick\":true,\"required\":false,\"exclude\":false,\"readonly\":true,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname17\\\/fieldname11)\",\"min\":\"\",\"max\":\"\",\"suffix\":\" \\u0e1a\\u0e32\\u0e17\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"dformat\":\"number\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname17\",\"shortlabel\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"index\":8,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"medium\",\"eq\":\"PREC(fieldname16*0.0089)*(fieldname11)+fieldname16\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":true,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"\",\"description\":\"\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_13\",\"evalequations\":0,\"evalequations_delay\":0,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"animation_effect\":\"fade\",\"customstyles\":\"#fbuilder .cff-button-field{text-align:center;}\\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}\\n\",\"direction\":\"ltr\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n<div class=\"clearer\"><\/div>\n<\/form>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-12ce532 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12ce532\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1e8fc7\" data-id=\"c1e8fc7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31fc1fc elementor-widget elementor-widget-image\" data-id=\"31fc1fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" data-sizes=\"(max-width: 940px) 100vw, 940px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 940px; --smush-placeholder-aspect-ratio: 940\/705;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fa76ee1\" data-id=\"fa76ee1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22526fd elementor-widget elementor-widget-heading\" data-id=\"22526fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19 INKSUB<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5486591 elementor-widget elementor-widget-text-editor\" data-id=\"5486591\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 INKSUB \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e2d\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 Printer Sublimation \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3344ecf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3344ecf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afbb5b0\" data-id=\"afbb5b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cfdcba gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"4cfdcba\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"kad-wp-gallery36\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-6 rowtight\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d39b3e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d39b3e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9710f9c\" data-id=\"9710f9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2db3b2d elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"2db3b2d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347224-1536x1152.jpg\" alt=\"mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347226-1536x1152.jpg\" alt=\"\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347229-1536x1152.jpg\" alt=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__31432727.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e34\u0e49\u0e2d Mimaki TS100\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347230-1536x1152.jpg\" alt=\"\u0e02\u0e19\u0e2a\u0e48\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879775.jpg\" alt=\"Mimaki printer \u0e2a\u0e2d\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879771.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879770.jpg\" alt=\"\u0e25\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Mimaki printer\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846928.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846925.jpg\" alt=\"\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6180f3b\" data-id=\"6180f3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-009b129 elementor-widget elementor-widget-heading\" data-id=\"009b129\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7f38b4 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c7f38b4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2d9706 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2d9706\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7034bc8\" data-id=\"7034bc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62996fc elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"62996fc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0948752323\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d832899\" data-id=\"d832899\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-955e965 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"955e965\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 @line \u0e40\u0e25\u0e22<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-690ea12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"690ea12\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1555a23\" data-id=\"1555a23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e88a8d2 elementor-widget elementor-widget-image\" data-id=\"e88a8d2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"525\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497.jpg\" class=\"attachment-large size-large wp-image-9236 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497.jpg 750w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497-300x210.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497-600x420.jpg 600w\" data-sizes=\"(max-width: 750px) 100vw, 750px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 750px; --smush-placeholder-aspect-ratio: 750\/525;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"525\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497.jpg\" class=\"attachment-large size-large wp-image-9236\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497.jpg 750w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497-300x210.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Hf5493f1e73a74efc817751c3a651b3497-600x420.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"9373\"]\n","protected":false},"featured_media":9987,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[121],"product_tag":[138,136,141,137,143,142,139,140],"class_list":{"0":"post-9956","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-121","7":"product_tag-138","8":"product_tag-136","9":"product_tag-141","10":"product_tag-137","11":"product_tag-143","12":"product_tag-142","13":"product_tag-139","14":"product_tag-140","16":"first","17":"instock","18":"shipping-taxable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 - Mimaki Thailand<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T02:23:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 - Mimaki Thailand\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg\",\"datePublished\":\"2023-06-29T02:24:15+00:00\",\"dateModified\":\"2023-07-10T02:23:50+00:00\",\"description\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" \/>\n<meta property=\"product:price:amount\" content=\"0\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 - Mimaki Thailand","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020","og_description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/","og_site_name":"Mimaki Thailand","article_modified_time":"2023-07-10T02:23:50+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 - Mimaki Thailand","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg","datePublished":"2023-06-29T02:24:15+00:00","dateModified":"2023-07-10T02:23:50+00:00","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c 3 \u0e2b\u0e31\u0e27\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/A3020-1.jpg","width":1000,"height":1000,"caption":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 A3020"},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-a3020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a","item":"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/"},{"@type":"ListItem","position":4,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A3020"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9956"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9956\/revisions"}],"predecessor-version":[{"id":9989,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9956\/revisions\/9989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/9987"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=9956"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=9956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=9956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}