{"id":9702,"date":"2023-06-26T09:39:14","date_gmt":"2023-06-26T02:39:14","guid":{"rendered":"https:\/\/mimaki-inksub.com\/en\/?post_type=product&#038;p=9702"},"modified":"2023-07-10T09:12:09","modified_gmt":"2023-07-10T02:12:09","slug":"printer-dtf","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/","title":{"rendered":"Mimaki DTF TxF150-75"},"content":{"rendered":"<h1>Mimaki DTF (direct-to-film) mimimaki TxF150-75<\/h1>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8974 size-full aligncenter\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275.jpg\" alt=\"\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e08\u0e32\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DFT\" width=\"1706\" height=\"960\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275.jpg 1706w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-300x169.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1024x576.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-768x432.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1536x864.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-600x338.jpg 600w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/><\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e19\u0e35\u0e49\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/p>\n<h2>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF<\/h2>\n<h3>1. \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\n<p>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\n<h3>2. \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?\u200b<\/h3>\n<p>\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21DFT \u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49<\/p>\n<h3>3. \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29, \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2f\u0e25\u0e2f \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32 \u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e36\u0e01 \u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\n<h3>4. \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07?<\/h3>\n<p>\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e \u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e \u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/p>\n<h3>5. \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e14?<\/h3>\n<p>\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e04\u0e21\u0e0a\u0e31\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32, \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14, \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e41\u0e25\u0e30 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e21\u0e32\u0e23\u0e22\u0e32\u0e17<\/p>\n<h2>\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\n<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e15\u0e32\u0e21\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49:<\/p>\n<ol>\n<li>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c: \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e01\u0e1b\u0e23\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e36\u0e01: \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e36\u0e01\u0e43\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/li>\n<li>\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c: \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48<\/li>\n<li>\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19: \u0e04\u0e27\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/li>\n<\/ol>\n<h2>\u0e2a\u0e23\u0e38\u0e1b<\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF (direct-to-film) TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c, \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32, \u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a, \u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n<h2>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07<\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e1a\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n<ol>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c: \u0e43\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e41\u0e23\u0e01 \u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e2b\u0e22\u0e32\u0e1a \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e: \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u00a0 \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/li>\n<li>\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e16\u0e39\u0e01\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e08\u0e32\u0e01\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e1a\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01 DTF \u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e41\u0e25\u0e30 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<\/li>\n<li>\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u00a0 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e32\u0e27\u0e19\u0e32<\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-8972 lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" width=\"225\" height=\"300\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-scaled.jpg 1920w\" data-sizes=\"(max-width: 225px) 100vw, 225px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\" \/><noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-8972\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" width=\"225\" height=\"300\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-8971 lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" width=\"225\" height=\"300\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-scaled.jpg 1920w\" data-sizes=\"(max-width: 225px) 100vw, 225px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\" \/><noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-8971\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" width=\"225\" height=\"300\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/noscript><\/p>\n<p>&nbsp;<\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9750\" class=\"elementor elementor-9750\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f07d586 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f07d586\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b995c\" data-id=\"27b995c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-895f34b elementor-widget elementor-widget-heading\" data-id=\"895f34b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF (direct-to-film) mimimaki TxF150-75<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-558479f elementor-widget elementor-widget-image\" data-id=\"558479f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1024x576.jpg\" class=\"attachment-large size-large wp-image-8974 lazyload\" alt=\"\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e08\u0e32\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DFT\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1024x576.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-300x169.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-768x432.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1536x864.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-600x338.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275.jpg 1706w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1024x576.jpg\" class=\"attachment-large size-large wp-image-8974\" alt=\"\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e08\u0e32\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DFT\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1024x576.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-300x169.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-768x432.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-1536x864.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275-600x338.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15155275.jpg 1706w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cc5fde elementor-widget elementor-widget-heading\" data-id=\"2cc5fde\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF (direct-to-film) TxF150-75: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc7c794 elementor-widget elementor-widget-text-editor\" data-id=\"dc7c794\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF (direct-to-film) \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e19\u0e35\u0e49\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a20d5ca elementor-widget elementor-widget-heading\" data-id=\"a20d5ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e4af3 elementor-widget elementor-widget-heading\" data-id=\"e1e4af3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-934bc7a elementor-widget elementor-widget-text-editor\" data-id=\"934bc7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4749b26 elementor-widget elementor-widget-heading\" data-id=\"4749b26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dbe297 elementor-widget elementor-widget-text-editor\" data-id=\"6dbe297\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21DFT \u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1597407 elementor-widget elementor-widget-heading\" data-id=\"1597407\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28d382a elementor-widget elementor-widget-text-editor\" data-id=\"28d382a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29, \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2f\u0e25\u0e2f \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32 \u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e36\u0e01 \u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9e284 elementor-widget elementor-widget-heading\" data-id=\"1c9e284\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07?<br><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f0a6a elementor-widget elementor-widget-text-editor\" data-id=\"62f0a6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e \u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e \u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc42770 elementor-widget elementor-widget-heading\" data-id=\"fc42770\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e14?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3319f35 elementor-widget elementor-widget-text-editor\" data-id=\"3319f35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e04\u0e21\u0e0a\u0e31\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32, \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14, \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d, \u0e41\u0e25\u0e30 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e21\u0e32\u0e23\u0e22\u0e32\u0e17<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a44494 elementor-widget elementor-widget-heading\" data-id=\"6a44494\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a908f1e elementor-widget elementor-widget-text-editor\" data-id=\"a908f1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e15\u0e32\u0e21\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49:<\/p><ol><li><p>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c: \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1d\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e01\u0e1b\u0e23\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p><\/li><li><p>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e36\u0e01: \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e36\u0e01\u0e43\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/p><\/li><li><p>\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c: \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48<\/p><\/li><li><p>\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19: \u0e04\u0e27\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/p><\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61b2034 elementor-widget elementor-widget-heading\" data-id=\"61b2034\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e23\u0e38\u0e1b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a393b elementor-widget elementor-widget-text-editor\" data-id=\"11a393b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF (direct-to-film) TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c, \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32, \u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a, \u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c06dfb6 elementor-widget elementor-widget-heading\" data-id=\"c06dfb6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf7e8d elementor-widget elementor-widget-text-editor\" data-id=\"bbf7e8d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e1a\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p><ol><li><p>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c: \u0e43\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e41\u0e23\u0e01 \u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e2b\u0e22\u0e32\u0e1a \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p><\/li><li><p>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e: \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u00a0 \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p><\/li><li><p>\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e16\u0e39\u0e01\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e08\u0e32\u0e01\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e1a\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01 DTF \u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e41\u0e25\u0e30 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<\/p><\/li><li><p>\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u00a0 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e32\u0e27\u0e19\u0e32<\/p><\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-c398ba0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c398ba0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-91780cf\" data-id=\"91780cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c132946 elementor-widget elementor-widget-image\" data-id=\"c132946\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg\" class=\"attachment-large size-large wp-image-8971 lazyload\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-scaled.jpg 1920w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg\" class=\"attachment-large size-large wp-image-8971\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745053-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1de887\" data-id=\"f1de887\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-134b6b9 elementor-widget elementor-widget-image\" data-id=\"134b6b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg\" class=\"attachment-large size-large wp-image-8972 lazyload\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-scaled.jpg 1920w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg\" class=\"attachment-large size-large wp-image-8972\" alt=\"OVP \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-768x1024.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-225x300.jpg 225w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1152x1536.jpg 1152w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-1536x2048.jpg 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-600x800.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__15745052-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5edffae elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5edffae\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5f96e5\" data-id=\"e5f96e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0337957 elementor-widget elementor-widget-heading\" data-id=\"0337957\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29<br>\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 0.89%<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 1 \u0e1b\u0e35<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9756b8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9756b8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71cafdc\" data-id=\"71cafdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35439da elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"35439da\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e705894\" data-id=\"e705894\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afe852f elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"afe852f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e7f298\" data-id=\"8e7f298\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ed4ce08 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"ed4ce08\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39eac90\" data-id=\"39eac90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-b5e128c elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"b5e128c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c457609\" data-id=\"c457609\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e3dec elementor-widget elementor-widget-heading\" data-id=\"12e3dec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e23\u0e35\u0e27\u0e34\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-266d05e elementor-hidden-mobile\" data-id=\"266d05e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a9e4053\" data-id=\"a9e4053\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac4ede4 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"ac4ede4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d47bffa\" data-id=\"d47bffa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9272f8 elementor-widget elementor-widget-heading\" data-id=\"b9272f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6b9ff5 elementor-hidden-mobile\" data-id=\"c6b9ff5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2add6c9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2add6c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f1ce58\" data-id=\"4f1ce58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a76c738 elementor-widget elementor-widget-image\" data-id=\"a76c738\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft.png\" class=\"attachment-full size-full wp-image-9141 lazyload\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 36\u0e07\u0e27\u0e14 dft\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-100x100.png 100w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft.png\" class=\"attachment-full size-full wp-image-9141\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 36\u0e07\u0e27\u0e14 dft\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-dft-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e7705e1\" data-id=\"e7705e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3fc992 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-calculated-fields-form\" data-id=\"d3fc992\" data-element_type=\"widget\" data-widget_type=\"calculated-fields-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>#fbuilder .cff-button-field{text-align:center;}\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"?\" method=\"post\" enctype=\"multipart\/form-data\" class=\"cff-form \"  dir=\"ltr\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/><pre style=\"display:none !important;\"><script type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname13\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fcurrency\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e32\\u0e04\\u0e32\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":false,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"currencySymbol\":\"\",\"currencyText\":\" \\u0e1a\\u0e32\\u0e17\",\"thousandSeparator\":\",\",\"centSeparator\":\".\",\"noCents\":true,\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":true,\"twoDecimals\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname18\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c %\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 30%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 35%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 40%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 45%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 50%\"],\"optgroup\":[false,false,false,false,false],\"choicesVal\":[\"0.30\",\"0.35\",\"0.40\",\"0.45\",\"0.50\"],\"choicesDep\":[[],[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname11\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e01\\u0e39\\u0e49\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"value\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 12 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 24 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 36 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"12 \",\"24 \",\"36 \"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname14\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fButton\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"sType\":\"calculate\",\"sValue\":\"\\u0e04\\u0e33\\u0e19\\u0e27\\u0e19\\u0e2a\\u0e34\\u0e19\\u0e40\\u0e0a\\u0e37\\u0e48\\u0e2d\",\"sOnclick\":\"\",\"sOnmousedown\":\"\",\"sLoading\":true,\"sMultipage\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname19\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname13*fieldname18)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname16\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"prec(fieldname13-fieldname19)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fnumber\",\"userhelp\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 0.89% \\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 %\",\"predefined\":\"0.89%\",\"predefinedClick\":true,\"required\":false,\"exclude\":false,\"readonly\":true,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname17\\\/fieldname11)\",\"min\":\"\",\"max\":\"\",\"suffix\":\" \\u0e1a\\u0e32\\u0e17\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"dformat\":\"number\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname17\",\"shortlabel\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"index\":8,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"medium\",\"eq\":\"PREC(fieldname16*0.0089)*(fieldname11)+fieldname16\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":true,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"\",\"description\":\"\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_13\",\"evalequations\":0,\"evalequations_delay\":0,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"animation_effect\":\"fade\",\"customstyles\":\"#fbuilder .cff-button-field{text-align:center;}\\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}\\n\",\"direction\":\"ltr\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n<div class=\"clearer\"><\/div>\n<\/form>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5da7414 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5da7414\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d7f4f34\" data-id=\"d7f4f34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d2dc12 elementor-widget elementor-widget-image\" data-id=\"1d2dc12\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" data-sizes=\"(max-width: 940px) 100vw, 940px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 940px; --smush-placeholder-aspect-ratio: 940\/705;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0801258\" data-id=\"0801258\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8e381f elementor-widget elementor-widget-heading\" data-id=\"e8e381f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19 INKSUB<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e828f41 elementor-widget elementor-widget-text-editor\" data-id=\"e828f41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 INKSUB \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e2d\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 Printer Sublimation \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7f170c9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f170c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3f7c00\" data-id=\"a3f7c00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8afad6a gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"8afad6a\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"kad-wp-gallery52\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-6 rowtight\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-45dc61b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45dc61b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d9bb531\" data-id=\"d9bb531\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d8d1c2 elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"8d8d1c2\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347224-1536x1152.jpg\" alt=\"mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347226-1536x1152.jpg\" alt=\"\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347229-1536x1152.jpg\" alt=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__31432727.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e34\u0e49\u0e2d Mimaki TS100\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347230-1536x1152.jpg\" alt=\"\u0e02\u0e19\u0e2a\u0e48\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879775.jpg\" alt=\"Mimaki printer \u0e2a\u0e2d\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879771.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879770.jpg\" alt=\"\u0e25\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Mimaki printer\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846928.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846925.jpg\" alt=\"\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b6e44f\" data-id=\"2b6e44f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4126ebc elementor-widget elementor-widget-heading\" data-id=\"4126ebc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3807a elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb3807a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cfabf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cfabf4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6292e90\" data-id=\"6292e90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f4f82a elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6f4f82a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0948752323\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d555a3b\" data-id=\"d555a3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60a147b elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"60a147b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 @line \u0e40\u0e25\u0e22<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"9373\"]\n","protected":false},"featured_media":9854,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[128],"product_tag":[132,135,134,130,131,129,133],"class_list":{"0":"post-9702","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dft","7":"product_tag-cotton","8":"product_tag-135","9":"product_tag-dft","10":"product_tag-130","11":"product_tag-131","12":"product_tag-129","13":"product_tag-133","15":"first","16":"instock","17":"shipping-taxable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF (direct-to-film) mimimaki TxF150-75<\/title>\n<meta name=\"description\" content=\"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mimaki DTF TxF150-75\" \/>\n<meta property=\"og:description\" content=\"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T02:12:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF (direct-to-film) mimimaki TxF150-75\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg\",\"datePublished\":\"2023-06-26T02:39:14+00:00\",\"dateModified\":\"2023-07-10T02:12:09+00:00\",\"description\":\"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF TxF150-75\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19Cotton\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99cotton\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mimaki DTF TxF150-75\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4cDFT\" \/>\n<meta property=\"product:price:amount\" content=\"0\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF (direct-to-film) mimimaki TxF150-75","description":"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/","og_locale":"en_US","og_type":"article","og_title":"Mimaki DTF TxF150-75","og_description":"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/","og_site_name":"Mimaki Thailand","article_modified_time":"2023-07-10T02:12:09+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c DTF (direct-to-film) mimimaki TxF150-75","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg","datePublished":"2023-06-26T02:39:14+00:00","dateModified":"2023-07-10T02:12:09+00:00","description":"Mimaki DTF TxF150-75 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/txf150.jpg","width":1000,"height":1000,"caption":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e34\u0e25\u0e4c\u0e21 DTF TxF150-75"},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-dtf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19Cotton","item":"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99cotton\/"},{"@type":"ListItem","position":4,"name":"Mimaki DTF TxF150-75"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4cDFT","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9702"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9702\/revisions"}],"predecessor-version":[{"id":9762,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9702\/revisions\/9762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/9854"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=9702"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=9702"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=9702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}