{"id":9627,"date":"2023-06-24T11:18:06","date_gmt":"2023-06-24T04:18:06","guid":{"rendered":"https:\/\/mimaki-inksub.com\/en\/?post_type=product&#038;p=9627"},"modified":"2023-10-12T11:46:05","modified_gmt":"2023-10-12T04:46:05","slug":"printer-f6430","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F6430"},"content":{"rendered":"<h1><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%A3%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%AA%E0%B8%B8%E0%B8%94_Epson_SureColor_SC-F6430%E2%80%8B\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Epson SureColor SC-F6430\u200b<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-9666 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1900\" height=\"500\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >\u0e2a\u0e32\u0e23\u0e1a\u0e31\u0e0d<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a049c4cb6845\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a049c4cb6845\"  type=\"checkbox\" id=\"item-6a049c4cb6845\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%A3%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%AA%E0%B8%B8%E0%B8%94_Epson_SureColor_SC-F6430%E2%80%8B\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Epson SureColor SC-F6430\u200b\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Epson SureColor SC-F6430\u200b<\/a><ul class='ez-toc-list-level-2'><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%9A%E0%B8%A3%E0%B8%A3%E0%B8%88%E0%B8%B8%E0%B8%AB%E0%B8%A1%E0%B8%B6%E0%B8%81%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88\" title=\"\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48\">\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%AB%E0%B8%99%E0%B9%89%E0%B8%B2%E0%B8%88%E0%B8%AD_LCD_%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88\" title=\"\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48\">\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%A3%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%AA%E0%B8%B8%E0%B8%94\" title=\"\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\">\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%9B%E0%B8%B1%E0%B8%8D%E0%B8%AB%E0%B8%B2%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%9E%E0%B8%9A%E0%B8%9A%E0%B9%88%E0%B8%AD%E0%B8%A2\" title=\"\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\">\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%9A%E0%B8%B5%E0%B9%89%E0%B8%A2%E0%B8%A7%E0%B8%AB%E0%B8%A3%E0%B8%B7%E0%B8%AD%E0%B9%80%E0%B8%A5%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%82%E0%B8%AD%E0%B8%87_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e02\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e02\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%84%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B8%94\" title=\"\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14\">\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%AA%E0%B8%B5%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%95%E0%B8%A3%E0%B8%87%E0%B8%95%E0%B8%B2%E0%B8%A1%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%95%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3\" title=\"\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\">\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%97%E0%B8%B3%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%8A%E0%B9%89%E0%B8%B2\" title=\"\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%AA%E0%B8%A1%E0%B9%88%E0%B8%B3%E0%B9%80%E0%B8%AA%E0%B8%A1%E0%B8%AD\" title=\"\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\">\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%95%E0%B8%B4%E0%B8%94\" title=\"\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14\">\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%95%E0%B8%B4%E0%B8%94_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%9B%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B9%84%E0%B8%94%E0%B9%89%E0%B8%87%E0%B9%88%E0%B8%B2%E0%B8%A2_%E0%B9%86\" title=\"\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46\">\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B9%89%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B9%88%E0%B8%AD%E0%B8%99%E0%B9%83%E0%B8%8A%E0%B9%89_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e08\u0e32\u0e01 Epson SureColor SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e21\u0e32\u0e08\u0e32\u0e01 \u0e23\u0e38\u0e48\u0e19 F6330\u00a0<span style=\"color: var( --e-global-color-text );\">\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9668 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg\" alt=\"\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1200\" height=\"1200\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-100x100.jpg 100w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1200;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-9668 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg\" alt=\"\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-100x100.jpg 100w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/noscript><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%9A%E0%B8%A3%E0%B8%A3%E0%B8%88%E0%B8%B8%E0%B8%AB%E0%B8%A1%E0%B8%B6%E0%B8%81%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88\"><\/span>\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: left;\">\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e1b\u0e30\u0e1b\u0e19 \u0e43\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e44\u0e14\u0e49<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9669 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg\" alt=\"\" width=\"1200\" height=\"1200\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-100x100.jpg 100w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1200;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-9669 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-100x100.jpg 100w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/noscript><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%AB%E0%B8%99%E0%B9%89%E0%B8%B2%E0%B8%88%E0%B8%AD_LCD_%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88\"><\/span>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e02\u0e19\u0e32\u0e14 4.3 \u0e19\u0e34\u0e49\u0e27<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9670 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg\" alt=\"\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1200\" height=\"1200\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-100x100.jpg 100w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1200;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9670 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg\" alt=\"\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-100x100.jpg 100w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/noscript><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%AB%E0%B8%B1%E0%B8%A7%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%A3%E0%B8%B8%E0%B9%88%E0%B8%99%E0%B9%83%E0%B8%AB%E0%B8%A1%E0%B9%88%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%AA%E0%B8%B8%E0%B8%94\"><\/span>\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: left;\">\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e23\u0e38\u0e48\u0e19 F6430 \u0e19\u0e35\u0e49 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Micro TFP \u0e02\u0e19\u0e32\u0e14 1.3 \u0e19\u0e34\u0e49\u0e27\u0e0a\u0e48\u0e27\u0e22 \u0e43\u0e2b\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e02\u0e36\u0e49\u0e19\u0e16\u0e36\u0e07 2 \u0e40\u0e17\u0e48\u0e32<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%9B%E0%B8%B1%E0%B8%8D%E0%B8%AB%E0%B8%B2%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%9E%E0%B8%9A%E0%B8%9A%E0%B9%88%E0%B8%AD%E0%B8%A2\"><\/span>\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%9A%E0%B8%B5%E0%B9%89%E0%B8%A2%E0%B8%A7%E0%B8%AB%E0%B8%A3%E0%B8%B7%E0%B8%AD%E0%B9%80%E0%B8%A5%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%82%E0%B8%AD%E0%B8%87_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e02\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2b\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07, \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19. \u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e27\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%84%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B8%94\"><\/span>\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14 \u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e21\u0e36\u0e01\u0e44\u0e21\u0e48\u0e1e\u0e2d. \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e36\u0e01 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%AA%E0%B8%B5%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%95%E0%B8%A3%E0%B8%87%E0%B8%95%E0%B8%B2%E0%B8%A1%E0%B8%97%E0%B8%B5%E0%B9%88%E0%B8%95%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3\"><\/span>\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e2a\u0e35 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e43\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e35 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e42\u0e2b\u0e21\u0e14\u0e2a\u0e35 CMYK \u0e41\u0e25\u0e30 RGB. \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%97%E0%B8%B3%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%A5%E0%B9%88%E0%B8%B2%E0%B8%8A%E0%B9%89%E0%B8%B2\"><\/span>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b , \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21, \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c. \u0e25\u0e14\u0e02\u0e19\u0e32\u0e14 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%84%E0%B8%A1%E0%B9%88%E0%B8%AA%E0%B8%A1%E0%B9%88%E0%B8%B3%E0%B9%80%E0%B8%AA%E0%B8%A1%E0%B8%AD\"><\/span>\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e36\u0e01 \u0e17\u0e35\u0e48\u0e21\u0e35 \u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e01\u0e1b\u0e23\u0e01, \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21. \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c, \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%95%E0%B8%B4%E0%B8%94\"><\/span>\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e14\u0e36\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e2d\u0e2d\u0e01 \u0e14\u0e36\u0e07\u0e40\u0e1a\u0e32 \u0e46 \u0e1b\u0e34\u0e14\u0e16\u0e32\u0e14\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u00a0 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e14\u0e39\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e44\u0e1f\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e41\u0e01\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e44\u0e02\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%94%E0%B8%B2%E0%B8%A9%E0%B8%95%E0%B8%B4%E0%B8%94_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_%E0%B8%9B%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B9%84%E0%B8%94%E0%B9%89%E0%B8%87%E0%B9%88%E0%B8%B2%E0%B8%A2_%E0%B9%86\"><\/span>\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e43\u0e2a\u0e41\u0e25\u0e30\u0e04\u0e21\u0e0a\u0e31\u0e14<\/li>\n<li>\u0e43\u0e0a\u0e49 \u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/li>\n<li>\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/li>\n<li>\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/li>\n<li>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/li>\n<li>\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30 \u0e17\u0e31\u0e19\u0e17\u0e48\u0e27\u0e07\u0e17\u0e35<\/li>\n<li>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/li>\n<li>\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/li>\n<li>\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e40 \u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B9%89%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B9%88%E0%B8%AD%E0%B8%99%E0%B9%83%E0%B8%8A%E0%B9%89_%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2a\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/li>\n<li>\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e21\u0e35 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2b\u0e21\u0e36\u0e01\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/li>\n<li>\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/li>\n<li>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e36\u0e01 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/li>\n<li>\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32 \u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e08\u0e23\u0e34\u0e07<\/li>\n<li>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/li>\n<li>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07<\/li>\n<li>\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9624\" class=\"elementor elementor-9624\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-24beaae elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24beaae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c227af\" data-id=\"6c227af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5605303 elementor-widget elementor-widget-heading\" data-id=\"5605303\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Epson SureColor SC-F6430<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08f46e6 elementor-widget elementor-widget-image\" data-id=\"08f46e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"269\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png\" class=\"attachment-large size-large wp-image-9666 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/269;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"269\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png\" class=\"attachment-large size-large wp-image-9666\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c749b elementor-widget elementor-widget-text-editor\" data-id=\"85c749b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e08\u0e32\u0e01 Epson SureColor SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e21\u0e32\u0e08\u0e32\u0e01 \u0e23\u0e38\u0e48\u0e19 F6330\u00a0<span style=\"color: var( --e-global-color-text );\">\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5bb193a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bb193a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8d1d40a\" data-id=\"8d1d40a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-918a488 elementor-widget elementor-widget-image\" data-id=\"918a488\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9668 lazyload\" alt=\"\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9668\" alt=\"\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e8ff5be\" data-id=\"e8ff5be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dda904 elementor-widget elementor-widget-heading\" data-id=\"5dda904\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5f6682 elementor-widget elementor-widget-text-editor\" data-id=\"a5f6682\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e1b\u0e30\u0e1b\u0e19 \u0e43\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e36\u0e01\u0e44\u0e14\u0e49\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc4cda0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc4cda0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5680501\" data-id=\"5680501\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3e29cb elementor-widget elementor-widget-heading\" data-id=\"f3e29cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc69c8d elementor-widget elementor-widget-text-editor\" data-id=\"cc69c8d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LCD \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e02\u0e19\u0e32\u0e14 4.3 \u0e19\u0e34\u0e49\u0e27<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3535821\" data-id=\"3535821\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5b8c05 elementor-widget elementor-widget-image\" data-id=\"d5b8c05\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9669 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9669\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cde45a5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cde45a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5bf3048\" data-id=\"5bf3048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f167f9 elementor-widget elementor-widget-image\" data-id=\"5f167f9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9670 lazyload\" alt=\"\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9670\" alt=\"\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/5.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-248a524\" data-id=\"248a524\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aa89e4 elementor-widget elementor-widget-heading\" data-id=\"5aa89e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-079904f elementor-widget elementor-widget-text-editor\" data-id=\"079904f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e23\u0e38\u0e48\u0e19 F6430 \u0e19\u0e35\u0e49 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Micro TFP \u0e02\u0e19\u0e32\u0e14 1.3 \u0e19\u0e34\u0e49\u0e27\u0e0a\u0e48\u0e27\u0e22 \u0e43\u0e2b\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e02\u0e36\u0e49\u0e19\u0e16\u0e36\u0e07 2 \u0e40\u0e17\u0e48\u0e32<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b86c14d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b86c14d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d36d2d7\" data-id=\"d36d2d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-346f18b elementor-widget elementor-widget-heading\" data-id=\"346f18b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e43\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d632ca6 elementor-widget elementor-widget-heading\" data-id=\"d632ca6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e02\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf5d3f elementor-widget elementor-widget-text-editor\" data-id=\"1bf5d3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2b\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07, \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19. \u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e27\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e43 \u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd33e40 elementor-widget elementor-widget-heading\" data-id=\"cd33e40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c4fe3d elementor-widget elementor-widget-text-editor\" data-id=\"3c4fe3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14 \u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e21\u0e36\u0e01\u0e44\u0e21\u0e48\u0e1e\u0e2d. \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e36\u0e01 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c52f3e6 elementor-widget elementor-widget-heading\" data-id=\"c52f3e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-293477a elementor-widget elementor-widget-text-editor\" data-id=\"293477a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e2a\u0e35 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e43\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e35 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e42\u0e2b\u0e21\u0e14\u0e2a\u0e35 CMYK \u0e41\u0e25\u0e30 RGB. \u0e04\u0e27\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42fe155 elementor-widget elementor-widget-heading\" data-id=\"42fe155\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a39a6b9 elementor-widget elementor-widget-text-editor\" data-id=\"a39a6b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b , \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21, \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c. \u0e25\u0e14\u0e02\u0e19\u0e32\u0e14 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87f840c elementor-widget elementor-widget-heading\" data-id=\"87f840c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1267bc5 elementor-widget elementor-widget-text-editor\" data-id=\"1267bc5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e36\u0e01 \u0e17\u0e35\u0e48\u0e21\u0e35 \u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e01\u0e1b\u0e23\u0e01, \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21. \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c, \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e25\u0e30 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeef75c elementor-widget elementor-widget-heading\" data-id=\"eeef75c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd4c346 elementor-widget elementor-widget-text-editor\" data-id=\"cd4c346\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e14\u0e36\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e2d\u0e2d\u0e01 \u0e14\u0e36\u0e07\u0e40\u0e1a\u0e32 \u0e46 \u0e1b\u0e34\u0e14\u0e16\u0e32\u0e14\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u00a0 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e14\u0e39\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e44\u0e1f\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e41\u0e01\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e44\u0e02\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1670246 elementor-widget elementor-widget-heading\" data-id=\"1670246\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e15\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f31eea5 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f31eea5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e43\u0e2a\u0e41\u0e25\u0e30\u0e04\u0e21\u0e0a\u0e31\u0e14<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e43\u0e0a\u0e49 \u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30 \u0e17\u0e31\u0e19\u0e17\u0e48\u0e27\u0e07\u0e17\u0e35<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e40 \u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-016d5ad elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"016d5ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ccf2ffb\" data-id=\"ccf2ffb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-715abf7 elementor-widget elementor-widget-heading\" data-id=\"715abf7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0bc08 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fb0bc08\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2a\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e17\u0e35\u0e48\u0e21\u0e35 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2b\u0e21\u0e36\u0e01\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e36\u0e01 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32 \u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e08\u0e23\u0e34\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9555983 elementor-widget elementor-widget-text-editor\" data-id=\"9555983\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 EPSON SC-F6430 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e48\u0e44\u0e14\u0e49 <a href=\"https:\/\/www.ink-sub.com\/p_29820_183155_868074_EPSON-F6430%2CF6430H.htm.\">\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f19cea elementor-widget elementor-widget-text-editor\" data-id=\"3f19cea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e14\u0e39\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46<a href=\"https:\/\/mimaki-inksub.com\/en\/\">\u00a0\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c87d99d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c87d99d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-493f745\" data-id=\"493f745\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c60d988 elementor-widget elementor-widget-heading\" data-id=\"c60d988\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29<br>\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 0.89%<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 1 \u0e1b\u0e35<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-b6c1d27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6c1d27\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8b3429f\" data-id=\"8b3429f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a891d52 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"a891d52\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c54a35c\" data-id=\"c54a35c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-167336f elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"167336f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b071cb\" data-id=\"8b071cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8c42fe5 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"8c42fe5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-83ef355\" data-id=\"83ef355\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-83e2191 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"83e2191\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ebccdfd\" data-id=\"ebccdfd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9861f7e elementor-widget elementor-widget-heading\" data-id=\"9861f7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e23\u0e35\u0e27\u0e34\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-40bf286 elementor-hidden-mobile\" data-id=\"40bf286\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ca03942\" data-id=\"ca03942\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-8df01e0 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"8df01e0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dfc7428\" data-id=\"dfc7428\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e87b89e elementor-widget elementor-widget-heading\" data-id=\"e87b89e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b289470 elementor-hidden-mobile\" data-id=\"b289470\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fb1d55e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb1d55e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c187250\" data-id=\"c187250\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a751e93 elementor-widget elementor-widget-image\" data-id=\"a751e93\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430.png\" class=\"attachment-full size-full wp-image-9660 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d f6430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-100x100.png 100w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430.png\" class=\"attachment-full size-full wp-image-9660\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d f6430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f6430-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3ca536\" data-id=\"d3ca536\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d1768d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-calculated-fields-form\" data-id=\"1d1768d\" data-element_type=\"widget\" data-widget_type=\"calculated-fields-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>#fbuilder .cff-button-field{text-align:center;}\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"?\" method=\"post\" enctype=\"multipart\/form-data\" class=\"cff-form \"  dir=\"ltr\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/><pre style=\"display:none !important;\"><script type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname13\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fcurrency\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e32\\u0e04\\u0e32\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":false,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"currencySymbol\":\"\",\"currencyText\":\" \\u0e1a\\u0e32\\u0e17\",\"thousandSeparator\":\",\",\"centSeparator\":\".\",\"noCents\":true,\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":true,\"twoDecimals\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname18\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c %\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 30%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 35%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 40%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 45%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 50%\"],\"optgroup\":[false,false,false,false,false],\"choicesVal\":[\"0.30\",\"0.35\",\"0.40\",\"0.45\",\"0.50\"],\"choicesDep\":[[],[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname11\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e01\\u0e39\\u0e49\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"value\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 12 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 24 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 36 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"12 \",\"24 \",\"36 \"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname14\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fButton\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"sType\":\"calculate\",\"sValue\":\"\\u0e04\\u0e33\\u0e19\\u0e27\\u0e19\\u0e2a\\u0e34\\u0e19\\u0e40\\u0e0a\\u0e37\\u0e48\\u0e2d\",\"sOnclick\":\"\",\"sOnmousedown\":\"\",\"sLoading\":true,\"sMultipage\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname19\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname13*fieldname18)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname16\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"prec(fieldname13-fieldname19)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fnumber\",\"userhelp\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 0.89% \\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 %\",\"predefined\":\"0.89%\",\"predefinedClick\":true,\"required\":false,\"exclude\":false,\"readonly\":true,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname17\\\/fieldname11)\",\"min\":\"\",\"max\":\"\",\"suffix\":\" \\u0e1a\\u0e32\\u0e17\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"dformat\":\"number\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname17\",\"shortlabel\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"index\":8,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"medium\",\"eq\":\"PREC(fieldname16*0.0089)*(fieldname11)+fieldname16\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":true,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"\",\"description\":\"\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_13\",\"evalequations\":0,\"evalequations_delay\":0,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"animation_effect\":\"fade\",\"customstyles\":\"#fbuilder .cff-button-field{text-align:center;}\\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}\\n\",\"direction\":\"ltr\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n<div class=\"clearer\"><\/div>\n<\/form>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7b64e84 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b64e84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88f7d36\" data-id=\"88f7d36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e859003 elementor-widget elementor-widget-image\" data-id=\"e859003\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" data-sizes=\"(max-width: 940px) 100vw, 940px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 940px; --smush-placeholder-aspect-ratio: 940\/705;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f117a92\" data-id=\"f117a92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1a83bb elementor-widget elementor-widget-heading\" data-id=\"c1a83bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19 INKSUB<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40c426e elementor-widget elementor-widget-text-editor\" data-id=\"40c426e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 INKSUB \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e2d\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 Printer Sublimation \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-87c0364 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87c0364\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d7e2e1\" data-id=\"6d7e2e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d152847 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"d152847\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"kad-wp-gallery24\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-6 rowtight\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-35b6366 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35b6366\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b970bab\" data-id=\"b970bab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86ca361 elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"86ca361\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__45834285.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__45834290.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__45834294.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f033a39\" data-id=\"f033a39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7157a40 elementor-widget elementor-widget-heading\" data-id=\"7157a40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ecc463 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9ecc463\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd1b204 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd1b204\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9fdf379\" data-id=\"9fdf379\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaf0f3f elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"aaf0f3f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0948752323\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ce3c0b\" data-id=\"6ce3c0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ea4ef1 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4ea4ef1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 @line \u0e40\u0e25\u0e22<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"9373\"]\n","protected":false},"featured_media":9647,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[121],"product_tag":[138,136,141,137,143,142,139,140],"class_list":{"0":"post-9627","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-121","7":"product_tag-138","8":"product_tag-136","9":"product_tag-141","10":"product_tag-137","11":"product_tag-143","12":"product_tag-142","13":"product_tag-139","14":"product_tag-140","16":"first","17":"instock","18":"shipping-taxable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 EPSON F6430<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F6430\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-12T04:46:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 EPSON F6430\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg\",\"datePublished\":\"2023-06-24T04:18:06+00:00\",\"dateModified\":\"2023-10-12T04:46:05+00:00\",\"description\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON F6430\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F6430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" \/>\n<meta property=\"product:price:amount\" content=\"0\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 EPSON F6430","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F6430","og_description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/","og_site_name":"Mimaki Thailand","article_modified_time":"2023-10-12T04:46:05+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 EPSON F6430","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg","datePublished":"2023-06-24T04:18:06+00:00","dateModified":"2023-10-12T04:46:05+00:00","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson SC-F6430 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19 F6330 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f6430.jpg","width":1000,"height":1000,"caption":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON F6430"},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-f6430\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a","item":"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/"},{"@type":"ListItem","position":4,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F6430"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9627"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9627\/revisions"}],"predecessor-version":[{"id":9631,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9627\/revisions\/9631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/9647"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=9627"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=9627"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=9627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}