{"id":9622,"date":"2023-06-24T11:04:12","date_gmt":"2023-06-24T04:04:12","guid":{"rendered":"https:\/\/mimaki-inksub.com\/en\/?post_type=product&#038;p=9622"},"modified":"2023-07-10T09:29:46","modified_gmt":"2023-07-10T02:29:46","slug":"printer-epson9430","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H"},"content":{"rendered":"<h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H\u200b<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-9666 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" width=\"1900\" height=\"500\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e30\u0e1a\u0e1a 2 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e35\u0e27\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 Epson Eage\u00a0 software \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 <strong><span><a onclick=\"read_toggle(1925112642, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1925112642\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1925112642\" style=\"display: none;\"><\/strong>\u0e43\u0e19\u0e15\u0e31\u0e27\u0e23\u0e38\u0e48\u0e19 H \u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e01\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e04\u0e37\u0e2d\u0e2a\u0e35\u0e1f\u0e39\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e2a\u0e35\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e1f\u0e39\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e31\u0e48\u0e07\u0e1b\u0e34\u0e14\u0e42\u0e2b\u0e21\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e1c\u0e25\u0e34\u0e15 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e27\u0e34\u0e48\u0e07\u0e21\u0e32\u0e23\u0e32\u0e18\u0e2d\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1c\u0e49\u0e32\u0e1b\u0e39 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e1a\u0e0b\u0e32\u0e15\u0e34\u0e19 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d\u0e41\u0e1a\u0e1a\u0e0a\u0e35\u0e1f\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e49\u0e32\u0e14\u0e34\u0e1a \u0e1c\u0e49\u0e32\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19 \u0e18\u0e07\u0e1b\u0e35\u0e01\u0e19\u0e01 \u0e18\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Epson LFP Accuting \u0e44\u0e27\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e19\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08 \u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e25\u0e07\u0e43\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e22\u0e47\u0e1a \u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e0a\u0e49\u0e07<strong><\/div><\/strong><\/p>\n<h2>F9430 \u0e41\u0e25\u0e30 F9430H \u0e2a\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/h2>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9685 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430\" width=\"400\" height=\"300\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430-300x225.png 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/300;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-9685 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430\" width=\"400\" height=\"300\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/noscript><\/p>\n<h2>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430<\/h2>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e1a\u0e1a 4 \u0e2a\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9686 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430h\" width=\"400\" height=\"300\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h-300x225.png 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/300;\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-9686 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430h\" width=\"400\" height=\"300\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/noscript><\/p>\n<h2>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430H<\/h2>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e1a\u0e1a 6 \u0e2a\u0e35 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e42\u0e2b\u0e21\u0e14 CMYKLcLm \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e21\u0e0a\u0e31\u0e14\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 SC-F6430 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<hr \/>\n<ul>\n<li>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e27\u0e49\u0e32\u0e07 64 \u0e19\u0e34\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/li>\n<li>\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07<\/li>\n<li>\u0e2b\u0e21\u0e36\u0e01 UltraChrome \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Precision Dot \u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e15\u0e34<\/li>\n<li>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e21\u0e49\u0e27\u0e19\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1b\u0e49\u0e32\u0e22\u0e1c\u0e49\u0e32 (soft signage) \u0e02\u0e19\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e16\u0e36\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a<\/li>\n<li>\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e48\u0e33 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e44\u0e1f\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 20 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e19<\/li>\n<li>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e32\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c Epson \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/li>\n<li>\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 On Site Service<\/li>\n<\/ul>\n<h2>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d<\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e34\u0e27\u0e1e\u0e37\u0e49\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e16\u0e49\u0e27\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e32\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e32\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\n<h2>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e07\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (sublimation printing) \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e14 (heat pressing) \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n<h2>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (Sublimation Printing)<\/h2>\n<p>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19&#8221; (sublimation ink) \u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46<strong><span><a onclick=\"read_toggle(307599530, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink307599530\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read307599530\" style=\"display: none;\"><\/strong> \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e14\u0e43\u0e2a \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e1c\u0e49\u0e32\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19&#8221; (sublimation paper) \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e2b\u0e21\u0e36\u0e01 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e35\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e4a\u0e32\u0e0b \u0e41\u0e25\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e39\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e41\u0e25\u0e30 \u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07<strong><\/div><\/strong><\/p>\n<h2>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14 (Heat Pressing)<\/h2>\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e27\u0e32\u0e07\u0e1a\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;<a href=\"https:\/\/mimaki-inksub.com\/en\/product\/heatroller190cm\/\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19<\/a>&#8221; (heat press machine) \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 <strong><span><a onclick=\"read_toggle(1747682277, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1747682277\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1747682277\" style=\"display: none;\"><\/strong>\u0e0b\u0e36\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e16\u0e39\u0e01\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e14\u0e25\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e21\u0e31\u0e19\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32<strong><\/div><\/strong><\/p>\n<h3>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46<\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/p>\n<h4>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h4>\n<p>\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1c\u0e48\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32<strong><span><a onclick=\"read_toggle(2041669538, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink2041669538\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read2041669538\" style=\"display: none;\"><\/strong> \u0e41\u0e1c\u0e48\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49<strong><\/div><\/strong><\/p>\n<h4>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22<\/h4>\n<p><a href=\"https:\/\/virgo-sport.com\/shop\/virgo-sport\/default.aspx?page=pages&amp;url=virgo-sport&amp;pgid=1271&amp;lang=TH\">\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32<\/a> \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 <strong><span><a onclick=\"read_toggle(1660765902, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1660765902\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1660765902\" style=\"display: none;\"><\/strong>\u0e1a\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e49\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<strong><\/div><\/strong><\/p>\n<h4>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<\/h4>\n<p>\u0e01\u0e32\u0e23\u0e19\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e32\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 <strong><span><a onclick=\"read_toggle(1435749261, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1435749261\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1435749261\" style=\"display: none;\"><\/strong>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e25\u0e07\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<strong><\/div><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9688 size-full lazyload\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430+F9430h\" width=\"1200\" height=\"1200\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-100x100.jpg 100w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1200;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9688 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430+F9430h\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg 1200w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-100x100.jpg 100w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/noscript><\/p>\n<h2>\u0e2a\u0e23\u0e38\u0e1b<\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<strong><span><a onclick=\"read_toggle(1715308698, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1715308698\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1715308698\" style=\"display: none;\"><\/strong> \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19 \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<strong><\/div><\/strong><\/p>\n<h2>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<\/h2>\n<h3>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07?<\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e16\u0e49\u0e27\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e1a\u0e1a\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e14\u0e49<\/p>\n<h3>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e30\u0e44\u0e23\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19?<\/h3>\n<p>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e14\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49<\/p>\n<h3>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?<\/h3>\n<p>\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e21\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\n<h3>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/h3>\n<p>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e32\u0e01 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e44\u0e14\u0e49\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e1a\u0e1a\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e14\u0e49<\/p>\n<h3>\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19?<\/h3>\n<p>\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e25\u0e07\u0e1a\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9619\" class=\"elementor elementor-9619\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8f37cb2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f37cb2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60e484b\" data-id=\"60e484b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f3760e elementor-widget elementor-widget-heading\" data-id=\"9f3760e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430,F9430H<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9fa460 elementor-widget elementor-widget-image\" data-id=\"f9fa460\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"269\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png\" class=\"attachment-large size-large wp-image-9666 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/269;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"269\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png\" class=\"attachment-large size-large wp-image-9666\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F6430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1024x269.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-300x79.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-768x202.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-1536x404.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430-600x158.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19-F6430.png 1900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb2b53 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fdb2b53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e30\u0e1a\u0e1a 2 \u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e35\u0e27\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14 Epson Eage\u00a0 software \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u00a0\u0e43\u0e19\u0e15\u0e31\u0e27\u0e23\u0e38\u0e48\u0e19 H \u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e01\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e04\u0e37\u0e2d\u0e2a\u0e35\u0e1f\u0e39\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e2a\u0e35\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e1f\u0e39\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e31\u0e48\u0e07\u0e1b\u0e34\u0e14\u0e42\u0e2b\u0e21\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e1c\u0e25\u0e34\u0e15 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e27\u0e34\u0e48\u0e07\u0e21\u0e32\u0e23\u0e32\u0e18\u0e2d\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1c\u0e49\u0e32\u0e1b\u0e39 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e1a\u0e0b\u0e32\u0e15\u0e34\u0e19 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d\u0e41\u0e1a\u0e1a\u0e0a\u0e35\u0e1f\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e49\u0e32\u0e14\u0e34\u0e1a \u0e1c\u0e49\u0e32\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19 \u0e18\u0e07\u0e1b\u0e35\u0e01\u0e19\u0e01 \u0e18\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Epson LFP Accuting \u0e44\u0e27\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e19\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08 \u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e25\u0e07\u0e43\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e22\u0e47\u0e1a \u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e0a\u0e49\u0e07<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79b5d2f elementor-widget elementor-widget-heading\" data-id=\"79b5d2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F9430 \u0e41\u0e25\u0e30 F9430H \u0e2a\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f07fe8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f07fe8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-561c5fb\" data-id=\"561c5fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27d59f0 elementor-widget elementor-widget-image\" data-id=\"27d59f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png\" class=\"attachment-large size-large wp-image-9685 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430-300x225.png 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png\" class=\"attachment-large size-large wp-image-9685\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-92c505c\" data-id=\"92c505c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ae67c5 elementor-widget elementor-widget-heading\" data-id=\"9ae67c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1411983 elementor-widget elementor-widget-text-editor\" data-id=\"1411983\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e1a\u0e1a 4 \u0e2a\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a1bcfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a1bcfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07eb62d\" data-id=\"07eb62d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b082e19 elementor-widget elementor-widget-image\" data-id=\"b082e19\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png\" class=\"attachment-large size-large wp-image-9686 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430h\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h-300x225.png 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png\" class=\"attachment-large size-large wp-image-9686\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430h\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h.png 400w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430h-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db36c0d\" data-id=\"db36c0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cadb8d4 elementor-widget elementor-widget-heading\" data-id=\"cadb8d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430H<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56d8e28 elementor-widget elementor-widget-text-editor\" data-id=\"56d8e28\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e1a\u0e1a 6 \u0e2a\u0e35 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e42\u0e2b\u0e21\u0e14 CMYKLcLm \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e21\u0e0a\u0e31\u0e14\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 SC-F6430 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d7f59 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"54d7f59\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e27\u0e49\u0e32\u0e07 64 \u0e19\u0e34\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2b\u0e21\u0e36\u0e01 UltraChrome \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Precision Dot \u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e15\u0e34<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e19\u0e21\u0e49\u0e27\u0e19\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1b\u0e49\u0e32\u0e22\u0e1c\u0e49\u0e32 (soft signage) \u0e02\u0e19\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e16\u0e36\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e48\u0e33 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e44\u0e1f\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 20 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e32\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c Epson \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 On Site Service<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eba987 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3eba987\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a382a59 elementor-widget elementor-widget-heading\" data-id=\"a382a59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8b034 elementor-widget elementor-widget-text-editor\" data-id=\"3d8b034\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e34\u0e27\u0e1e\u0e37\u0e49\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e16\u0e49\u0e27\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e32\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e32\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cde4b2a elementor-widget elementor-widget-heading\" data-id=\"cde4b2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfcc8c5 elementor-widget elementor-widget-text-editor\" data-id=\"dfcc8c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e07\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (sublimation printing) \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e14 (heat pressing) \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35310e4 elementor-widget elementor-widget-heading\" data-id=\"35310e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (Sublimation Printing)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30ef23 elementor-widget elementor-widget-text-editor\" data-id=\"f30ef23\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19&#8221; (sublimation ink) \u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e14\u0e43\u0e2a \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e1c\u0e49\u0e32\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19&#8221; (sublimation paper) \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e2b\u0e21\u0e36\u0e01 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e35\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e4a\u0e32\u0e0b \u0e41\u0e25\u0e30\u0e0b\u0e36\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e39\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e41\u0e25\u0e30 \u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3516a6 elementor-widget elementor-widget-heading\" data-id=\"f3516a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14 (Heat Pressing)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f50017e elementor-widget elementor-widget-text-editor\" data-id=\"f50017e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e30\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e27\u0e32\u0e07\u0e1a\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19&#8221; (heat press machine) \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e0b\u0e36\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e16\u0e39\u0e01\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e14\u0e25\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e21\u0e31\u0e19\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbcfa39 elementor-widget elementor-widget-heading\" data-id=\"cbcfa39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56ab84d elementor-widget elementor-widget-text-editor\" data-id=\"56ab84d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d645109 elementor-widget elementor-widget-heading\" data-id=\"d645109\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ada18 elementor-widget elementor-widget-text-editor\" data-id=\"42ada18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1c\u0e48\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e1c\u0e48\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-889f9e3 elementor-widget elementor-widget-heading\" data-id=\"889f9e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e158d85 elementor-widget elementor-widget-text-editor\" data-id=\"e158d85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e1a\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e49\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c371e35 elementor-widget elementor-widget-heading\" data-id=\"c371e35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6229cc8 elementor-widget elementor-widget-text-editor\" data-id=\"6229cc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e01\u0e32\u0e23\u0e19\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e32\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e25\u0e07\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-937a9d6 elementor-widget elementor-widget-image\" data-id=\"937a9d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9688 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430+F9430h\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9688\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 F9430+F9430h\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-1024x1024.jpg 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-768x768.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/Ee3BwU6U8AAzuJN.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8620783 elementor-widget elementor-widget-heading\" data-id=\"8620783\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e23\u0e38\u0e1b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b30034 elementor-widget elementor-widget-text-editor\" data-id=\"0b30034\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19 \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4518499 elementor-widget elementor-widget-heading\" data-id=\"4518499\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc463a elementor-widget elementor-widget-toggle\" data-id=\"9cc463a\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1641\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1641\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1641\"><p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49 \u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e16\u0e49\u0e27\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e1a\u0e1a\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e14\u0e49<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1642\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1642\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e30\u0e44\u0e23\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1642\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1642\"><p>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e14\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e2b\u0e21\u0e36\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1643\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1643\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1643\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1643\"><p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e21\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1644\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1644\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1644\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1644\"><p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e32\u0e01 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e44\u0e14\u0e49\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e1a\u0e1a\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e44\u0e14\u0e49\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1645\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1645\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1645\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1645\"><p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e25\u0e07\u0e1a\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0de2cfa elementor-widget elementor-widget-text-editor\" data-id=\"0de2cfa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e14\u0e39\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19 EPSON SC-F9430 \u0e44\u0e14\u0e49 <a href=\"https:\/\/www.ink-sub.com\/p_29820_183155_868074_EPSON-F6430%2CF6430H.htm\">\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-064a1d2 elementor-widget elementor-widget-text-editor\" data-id=\"064a1d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e14\u0e39\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e21\u0e34\u0e21\u0e32\u0e01\u0e34\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"https:\/\/mimaki-inksub.com\/en\">\u0e40\u0e27\u0e47\u0e1a\u0e19\u0e35\u0e49<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0acdf8d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0acdf8d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67dbfdb\" data-id=\"67dbfdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-911ae9f elementor-widget elementor-widget-heading\" data-id=\"911ae9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29<br>\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 0.89%<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 1 \u0e1b\u0e35<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-920748c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"920748c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5cd412b\" data-id=\"5cd412b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8455a89 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"8455a89\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c496563\" data-id=\"c496563\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d63ea elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"17d63ea\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ce26aa3\" data-id=\"ce26aa3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-37c1dd0 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"37c1dd0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68da6eb\" data-id=\"68da6eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb91f94 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"fb91f94\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ffa74ad\" data-id=\"ffa74ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1359c42 elementor-widget elementor-widget-heading\" data-id=\"1359c42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e23\u0e35\u0e27\u0e34\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e8f5020 elementor-hidden-mobile\" data-id=\"e8f5020\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e442663\" data-id=\"e442663\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5067dcb elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"5067dcb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a184182\" data-id=\"a184182\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ec2abd elementor-widget elementor-widget-heading\" data-id=\"1ec2abd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8dce426 elementor-hidden-mobile\" data-id=\"8dce426\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6692a89 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6692a89\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bccaf1\" data-id=\"4bccaf1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f65104 elementor-widget elementor-widget-image\" data-id=\"0f65104\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430.png\" class=\"attachment-full size-full wp-image-9663 lazyload\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d f9430\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-100x100.png 100w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430.png\" class=\"attachment-full size-full wp-image-9663\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d f9430\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-f9430-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-180b4eb\" data-id=\"180b4eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf997d5 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-calculated-fields-form\" data-id=\"bf997d5\" data-element_type=\"widget\" data-widget_type=\"calculated-fields-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>#fbuilder .cff-button-field{text-align:center;}\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"?\" method=\"post\" enctype=\"multipart\/form-data\" class=\"cff-form \"  dir=\"ltr\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/><pre style=\"display:none !important;\"><script type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname13\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fcurrency\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e32\\u0e04\\u0e32\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":false,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"currencySymbol\":\"\",\"currencyText\":\" \\u0e1a\\u0e32\\u0e17\",\"thousandSeparator\":\",\",\"centSeparator\":\".\",\"noCents\":true,\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":true,\"twoDecimals\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname18\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c %\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 30%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 35%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 40%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 45%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 50%\"],\"optgroup\":[false,false,false,false,false],\"choicesVal\":[\"0.30\",\"0.35\",\"0.40\",\"0.45\",\"0.50\"],\"choicesDep\":[[],[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname11\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e01\\u0e39\\u0e49\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"value\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 12 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 24 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 36 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"12 \",\"24 \",\"36 \"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname14\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fButton\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"sType\":\"calculate\",\"sValue\":\"\\u0e04\\u0e33\\u0e19\\u0e27\\u0e19\\u0e2a\\u0e34\\u0e19\\u0e40\\u0e0a\\u0e37\\u0e48\\u0e2d\",\"sOnclick\":\"\",\"sOnmousedown\":\"\",\"sLoading\":true,\"sMultipage\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname19\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname13*fieldname18)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname16\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"prec(fieldname13-fieldname19)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fnumber\",\"userhelp\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 0.89% \\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 %\",\"predefined\":\"0.89%\",\"predefinedClick\":true,\"required\":false,\"exclude\":false,\"readonly\":true,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname17\\\/fieldname11)\",\"min\":\"\",\"max\":\"\",\"suffix\":\" \\u0e1a\\u0e32\\u0e17\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"dformat\":\"number\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname17\",\"shortlabel\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"index\":8,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"medium\",\"eq\":\"PREC(fieldname16*0.0089)*(fieldname11)+fieldname16\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":true,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"\",\"description\":\"\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_13\",\"evalequations\":0,\"evalequations_delay\":0,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"animation_effect\":\"fade\",\"customstyles\":\"#fbuilder .cff-button-field{text-align:center;}\\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}\\n\",\"direction\":\"ltr\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n<div class=\"clearer\"><\/div>\n<\/form>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-361f2bc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"361f2bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f6e9995\" data-id=\"f6e9995\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3d3f42 elementor-widget elementor-widget-image\" data-id=\"d3d3f42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" data-sizes=\"(max-width: 940px) 100vw, 940px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 940px; --smush-placeholder-aspect-ratio: 940\/705;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"705\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b387a3\" data-id=\"3b387a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc1d8e6 elementor-widget elementor-widget-heading\" data-id=\"dc1d8e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19 INKSUB<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09733bd elementor-widget elementor-widget-text-editor\" data-id=\"09733bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 INKSUB \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e2d\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 Printer Sublimation \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-70d6e71 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70d6e71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2bd26e\" data-id=\"f2bd26e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aca0fa5 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"aca0fa5\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"kad-wp-gallery18\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-6 rowtight\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5304d5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5304d5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30c6fce\" data-id=\"30c6fce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6360b4 elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"c6360b4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347224-1536x1152.jpg\" alt=\"mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347226-1536x1152.jpg\" alt=\"\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347229-1536x1152.jpg\" alt=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__31432727.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e34\u0e49\u0e2d Mimaki TS100\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347230-1536x1152.jpg\" alt=\"\u0e02\u0e19\u0e2a\u0e48\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879775.jpg\" alt=\"Mimaki printer \u0e2a\u0e2d\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879771.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879770.jpg\" alt=\"\u0e25\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Mimaki printer\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846928.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846925.jpg\" alt=\"\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-524fef4\" data-id=\"524fef4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f2967 elementor-widget elementor-widget-heading\" data-id=\"e0f2967\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ecd36e elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6ecd36e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9859042 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9859042\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ce8f4d\" data-id=\"9ce8f4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9035932 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9035932\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0948752323\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-632ba2d\" data-id=\"632ba2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac3986b elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ac3986b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 @line \u0e40\u0e25\u0e22<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"9373\"]\n","protected":false},"featured_media":9648,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[121],"product_tag":[138,136,141,137,143,142,139,140],"class_list":{"0":"post-9622","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-121","7":"product_tag-138","8":"product_tag-136","9":"product_tag-141","10":"product_tag-137","11":"product_tag-143","12":"product_tag-142","13":"product_tag-139","14":"product_tag-140","16":"first","17":"instock","18":"shipping-taxable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 SC-F9430, SC-F9430H<\/title>\n<meta name=\"description\" content=\"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H\" \/>\n<meta property=\"og:description\" content=\"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T02:29:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 SC-F9430, SC-F9430H\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg\",\"datePublished\":\"2023-06-24T04:04:12+00:00\",\"dateModified\":\"2023-07-10T02:29:46+00:00\",\"description\":\"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON F9430\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" \/>\n<meta property=\"product:price:amount\" content=\"0\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 SC-F9430, SC-F9430H","description":"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H","og_description":"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/","og_site_name":"Mimaki Thailand","article_modified_time":"2023-07-10T02:29:46+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 SC-F9430, SC-F9430H","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg","datePublished":"2023-06-24T04:04:12+00:00","dateModified":"2023-07-10T02:29:46+00:00","description":"EPSON SC-F9430, SC-F9430H \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27 H \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1f\u0e39\u0e25\u0e2d\u0e2d\u0e40\u0e23\u0e2a\u0e40\u0e0b\u0e19\u0e15\u0e4c","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/f9430.jpg","width":1000,"height":1000,"caption":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 EPSON F9430"},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-epson9430\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a","item":"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/"},{"@type":"ListItem","position":4,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Epson F9430,F9430H"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9622"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9622\/revisions"}],"predecessor-version":[{"id":9649,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/9622\/revisions\/9649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/9648"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=9622"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=9622"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=9622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}