{"id":1080,"date":"2021-01-22T04:46:29","date_gmt":"2021-01-22T04:46:29","guid":{"rendered":"https:\/\/www.peggo-industrial.com\/?post_type=product&#038;p=1080"},"modified":"2021-05-11T04:21:11","modified_gmt":"2021-05-11T04:21:11","slug":"%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS"},"content":{"rendered":"<h1><a href=\"https:\/\/www.youtube.com\/watch?v=8pf1nHVRu98\"><span style=\"color: #000080;\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS<\/span><\/a><\/h1>\n<p>\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e08\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01<\/p>\n<p>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e2b\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e07\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e27\u0e34\u0e16\u0e35\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d<a href=\"https:\/\/mimaki-inksub.com\/en\/product\/%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%AA%E0%B8%81%E0%B8%A3%E0%B8%B5%E0%B8%99%E0%B9%80%E0%B8%AA%E0%B8%B7%E0%B9%89%E0%B8%AD-iron-heat-tranfers\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d <\/a>\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22 \u0e46 \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u00a0\u0e21\u0e35\u00a03\u00a0\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u00a0\u0e41\u0e15\u0e48\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e08\u0e30\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e44\u0e1b<\/p>\n<p>\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e2d\u0e43\u0e08 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e44\u0e14\u0e49 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n<p>1.\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e01\u0e23\u0e35\u0e19 ( Silk Screen ) \u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e41\u0e1a\u0e1a\u0e43\u0e0a\u0e49\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07 \u0e1c\u0e49\u0e32\u0e2a\u0e35\u0e41\u0e01\u0e48 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47 \u0e1c\u0e49\u0e32\u0e2a\u0e35\u0e2d\u0e48\u0e2d\u0e19<\/p>\n<p>\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e46 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e2a\u0e39\u0e07 \u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e2b\u0e32\u0e01\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e21\u0e35 3 \u0e2a\u0e35<\/p>\n<p>\u0e08\u0e33\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 3 \u0e1a\u0e25\u0e47\u0e2d\u0e01 \u0e16\u0e49\u0e32\u0e40\u0e01\u0e34\u0e14\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e01\u0e47\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e40\u0e14\u0e34\u0e21\u0e44\u0e14\u0e49<\/p>\n<p>2.\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 (Direct to Garment) \u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u00a0\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1c\u0e49\u0e32\u00a0\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e19\u0e35\u0e49<\/p>\n<p>\u0e08\u0e33\u0e01\u0e31\u0e14\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1c\u0e49\u0e32 Cotton 100 % \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e2a\u0e35\u0e2d\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47 \u0e1c\u0e49\u0e32\u0e2a\u0e35\u0e40\u0e02\u0e49\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e04\u0e21\u0e0a\u0e31\u0e14<\/p>\n<p>\u0e43\u0e0a\u0e49\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e2a\u0e39\u0e07 \u0e02\u0e19\u0e32\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e08\u0e30\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e02\u0e19\u0e32\u0e14\u0e17\u0e35\u0e48 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 50 \u0e40\u0e0b\u0e19\u0e15\u0e34\u0e40\u0e21\u0e15\u0e23 * 50 \u0e40\u0e0b\u0e19\u0e15\u0e34\u0e40\u0e21\u0e15\u0e23<\/p>\n<p>3. \u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 ( Heat Transfer ) \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e35\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 \u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 ( Sublimation ) ,\u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c ( Transfer ) , \u0e40\u0e1f\u0e25\u0e47\u0e01 ( Flex ) \u0e41\u0e25\u0e30 \u0e01\u0e47\u0e1f\u0e25\u0e47\u0e2d\u0e01 ( Flox )<\/p>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e35\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 ( Heat Press ) \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e35\u0e49\u0e08\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e2b\u0e21\u0e39\u0e48 \u0e22\u0e48\u0e2d\u0e22\u0e25\u0e07\u0e44\u0e1b\u0e2d\u0e35\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e32\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e02\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49<\/p>\n<p>\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 ( Heat Transfer ) \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e39\u0e14\u0e27\u0e48\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e19\u0e35\u0e49\u0e21\u0e35\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n<p>3.1. \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 ( Sublimation )<\/p>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e17\u0e35\u0e48\u0e22\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (Sublimation) \u0e08\u0e30\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07 \u0e41\u0e01\u0e49\u0e27 ,\u0e08\u0e32\u0e19 ,\u0e40\u0e04\u0e2a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c , \u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 , \u0e41\u0e1c\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e32\u0e2a\u0e4c<\/p>\n<p>\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e49\u0e32 \u0e2d\u0e37\u0e48\u0e19\u0e46\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e01\u0e49\u0e27 ,\u0e08\u0e32\u0e19 , \u0e40\u0e04\u0e2a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e04\u0e27\u0e23\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e16\u0e36\u0e07\u0e08\u0e30\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49<\/p>\n<p>\u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e49\u0e32\u0e2a\u0e35\u0e02\u0e32\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e19\u0e31\u0e49\u0e19<\/p>\n<p>\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e49\u0e32\u0e17\u0e35\u0e40\u0e04 ( TK ) \u00a0\u0e1c\u0e49\u0e32\u0e44\u0e19\u0e25\u0e2d\u0e19 ( Nylon ) \u0e1c\u0e49\u0e32\u0e1e\u0e2d\u0e25\u0e34\u0e40\u0e2d\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e4c ( Polyester ) \u0e1c\u0e49\u0e32\u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 ( Acrylic ) \u00a0\u0e1c\u0e49\u0e32\u0e2a\u0e41\u0e1b\u0e19\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e4c ( Spandex ) \u0e2b\u0e23\u0e37\u0e2d \u0e44\u0e25\u0e04\u0e23\u0e32 ( Lycra )<\/p>\n<p>\u0e1c\u0e49\u0e32\u0e0b\u0e35\u0e1f\u0e2d\u0e07 ( Chiffon ) \u00a0\u0e1c\u0e49\u0e32\u0e0b\u0e32\u0e15\u0e34\u0e19 ( satin fabric ) \u00a0\u0e1c\u0e49\u0e32\u0e17\u0e35\u0e0b\u0e35 ( TC ) \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e2d\u0e15\u0e15\u0e2d\u0e19 ( Cotton) \u0e1c\u0e2a\u0e21\u0e2d\u0e22\u0e39\u0e48 \u0e2d\u0e32\u0e08\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e2a\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e21\u0e48\u0e0a\u0e31\u0e14\u0e41\u0e08\u0e49\u0e07 \u0e44\u0e2b\u0e21\u0e40\u0e02\u0e49\u0e21\u0e40\u0e17\u0e48\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32<\/p>\n<p>\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 100 % \u0e1c\u0e49\u0e32\u0e41\u0e04\u0e19\u0e27\u0e32\u0e2a ( Canvas ) \u0e2f<\/p>\n<p>3.2. \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c (Transfer )<\/p>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e1c\u0e49\u0e32\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e19\u0e39\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19\u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c ( Transfer ) \u0e08\u0e30\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22 \u0e46<\/p>\n<p>\u0e22\u0e32\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e14\u0e44\u0e14\u0e49 \u0e23\u0e39\u0e1b\u0e07\u0e32\u0e19\u0e08\u0e30\u0e44\u0e21\u0e48\u0e41\u0e15\u0e01 \u0e07\u0e32\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e01\u0e27\u0e48\u0e32 \u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e01\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e08\u0e30\u0e21\u0e35\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 ( Sublimation )<\/p>\n<p>3.3. \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e40\u0e1f\u0e25\u0e47\u0e01 ( Flex ) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1f\u0e25\u0e47\u0e2d\u0e01 ( Flox )<\/p>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e2a\u0e35 \u0e17\u0e38\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e19\u0e39\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e04\u0e25\u0e49\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c (Transfer) \u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1f\u0e25\u0e47\u0e01\u0e1e\u0e35\u0e22\u0e39 ( Flex PU ) , ( Flex Metallic )<\/p>\n<p>\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e2d\u0e35\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e1f\u0e2d\u0e22\u0e25\u0e4c ( Foil ) , \u0e40\u0e1f\u0e25\u0e47\u0e01\u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21 ( Flex Hologram ) \u0e41\u0e25\u0e30 \u0e01\u0e47\u0e1f\u0e25\u0e47\u0e2d\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e2d\u0e35\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e1c\u0e49\u0e32\u0e01\u0e33\u0e21\u0e30\u0e2b\u0e22\u0e35\u0e48 ( Flox ) \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e30\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e44\u0e1b<\/p>\n<p>\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e32\u0e07\u0e41\u0e1a\u0e1a (Design) \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (fashion) \u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e15\u0e31\u0e27\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e19\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 heat transfer \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1c\u0e34\u0e27\u0e23\u0e32\u0e1a\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e1a\u0e32\u0e07\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e1a\u0e32\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e08\u0e30\u0e02\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 heat transfer \u0e01\u0e47\u0e40\u0e25\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d<\/p>\n<p>\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e49\u0e32\u0e2a\u0e4c \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e44\u0e21\u0e49 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e49\u0e32 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e25\u0e07\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e49\u0e32\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"module_sku\">\n<div class=\"widget-main-action widget-main-action-ws module-mainAction-lite module-mainAction-lite-vb detail-mainscreen-center-grid\" data-role=\"widget-main-action\" data-spm-anchor-id=\"a2700.wholesale.0.i29.2f402b2eOXzgbr\">\n<div class=\"ma-brief-list ma-main-brief-list\" data-role=\"ma-brief-list\">\n<div id=\"skuWrap\" class=\"sku-wrap\">\n<dl class=\"sku-attr-dl util-clearfix TEXT\" data-role=\"last-sku-attr\">\n<dd class=\"sku-attr-val value util-clearfix\">\n<div class=\"sku-attr-val-item \" data-id=\"100006014:-2;\" data-role=\"sku-attr-val\"><\/div>\n<\/dd>\n<\/dl>\n<div><strong>Warranty:<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"module_market_action\">\n<div class=\"module-market-action detail-mainscreen-center-grid\">\n<dl class=\"warrancy-widget \">\n<dd class=\"market-action-list__dd\"><b>1 year <\/b>for machinery warranty\u00a0<i class=\"next-icon next-icon-prompt next-small help-icon\" aria-haspopup=\"true\" aria-expanded=\"false\"><\/i><\/dd>\n<\/dl>\n<dl class=\"do-entry-item sample\">\n<dd class=\"do-entry-item-val\" title=\"sample\"><span style=\"font-weight: bold;\">Usage:<\/span><\/dd>\n<\/dl>\n<dl class=\"customize customize-list\">\n<dd class=\"value market-action-list__dd\">\n<div class=\"customization-list-item\" data-spm-anchor-id=\"a2700.wholesale.0.i28.2f402b2eOXzgbr\">\n<dl class=\"do-entry-item\">\n<dd class=\"do-entry-item-val\">\n<div class=\"text-ellipsis\" title=\"logo printer, mug printer\">printer sublimation<\/div>\n<\/dd>\n<\/dl>\n<dl class=\"do-entry-item\">\n<dt class=\"do-entry-item\"><span class=\"attr-name J-attr-name\" title=\"Voltage\">Voltage:<\/span><\/dt>\n<dd class=\"do-entry-item-val\">\n<div class=\"text-ellipsis\" title=\"220V\/210V\">220V\/210V<\/div>\n<\/dd>\n<\/dl>\n<dl class=\"do-entry-item\">\n<dt class=\"do-entry-item\"><span class=\"attr-name J-attr-name\" title=\"Dimensions(L*W*H)\">Dimensions(L*W*H):<\/span><\/dt>\n<dd class=\"do-entry-item-val\">\n<div class=\"text-ellipsis\" title=\"310*355*340mm\" data-spm-anchor-id=\"a2700.wholesale.0.i32.2f402b2eOXzgbr\">310*355*340mm<\/div>\n<\/dd>\n<\/dl>\n<dl class=\"do-entry-item\">\n<dt class=\"do-entry-item\"><span class=\"attr-name J-attr-name\" title=\"Weight\">Weight:<\/span><\/dt>\n<dd class=\"do-entry-item-val\">\n<div class=\"text-ellipsis\" title=\"4.7kg\" data-spm-anchor-id=\"a2700.wholesale.0.i39.2f402b2eOXzgbr\">4.7kg<\/div>\n<\/dd>\n<\/dl>\n<\/div>\n<\/dd>\n<\/dl>\n<\/div>\n<\/div>\n","protected":false},"featured_media":1060,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[64],"product_tag":[],"class_list":{"0":"post-1080","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-heat-sme","8":"first","9":"instock","10":"sale","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS, \u0e0a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d-iron-heat-tranfers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d-iron-heat-tranfers\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T04:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2501\" \/>\n\t<meta property=\"og:image:height\" content=\"2501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#3647;6,900\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS, \u0e0a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg\",\"datePublished\":\"2021-01-22T04:46:29+00:00\",\"dateModified\":\"2021-05-11T04:21:11+00:00\",\"description\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg\",\"width\":2501,\"height\":2501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"heat-sme\" \/>\n<meta property=\"product:price:amount\" content=\"6900\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS, \u0e0a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d-iron-heat-tranfers\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS","og_description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d-iron-heat-tranfers\/","og_site_name":"Mimaki Thailand","article_modified_time":"2021-05-11T04:21:11+00:00","og_image":[{"width":2501,"height":2501,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&#3647;6,900","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS, \u0e0a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg","datePublished":"2021-01-22T04:46:29+00:00","dateModified":"2021-05-11T04:21:11+00:00","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e18\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e41\u0e1a\u0e25\u0e47\u0e01\u0e14\u0e23\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2021\/01\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_iron-heat.jpg","width":2501,"height":2501},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b9%80%e0%b8%aa%e0%b8%b7%e0%b9%89%e0%b8%ad-iron-heat-tranfers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d IRON HEAT TRANFERS"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"heat-sme","product_price_amount":"6900","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/1080"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/1080\/revisions"}],"predecessor-version":[{"id":4189,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/1080\/revisions\/4189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/1060"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=1080"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}