{"id":10051,"date":"2023-07-04T11:20:00","date_gmt":"2023-07-04T04:20:00","guid":{"rendered":"https:\/\/mimaki-inksub.com\/en\/?post_type=product&#038;p=10051"},"modified":"2023-09-22T10:08:39","modified_gmt":"2023-09-22T03:08:39","slug":"printer-arena-a1522-2","status":"publish","type":"product","link":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522"},"content":{"rendered":"<h1><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_Arena_A1522\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-9654 size-full\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena.png\" alt=\"Arena A1522\" width=\"1920\" height=\"437\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena.png 1920w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena-300x68.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena-1024x233.png 1024w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena-768x175.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena-1536x350.png 1536w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1b\u0e01\u0e22\u0e32\u0e27-arena-600x137.png 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >\u0e2a\u0e32\u0e23\u0e1a\u0e31\u0e0d<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a049c952603e\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a049c952603e\"  type=\"checkbox\" id=\"item-6a049c952603e\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99_Arena_A1522\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522<\/a><ul class='ez-toc-list-level-2'><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B9%80%E0%B8%97%E0%B8%84%E0%B9%82%E0%B8%99%E0%B9%82%E0%B8%A5%E0%B8%A2%E0%B8%B5%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%84%E0%B8%B7%E0%B8%AD%E0%B8%AD%E0%B8%B0%E0%B9%84%E0%B8%A3\" title=\"\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23\">\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%9A%E0%B8%A7%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%97%E0%B8%B3%E0%B9%84%E0%B8%A1%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%95%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%A5%E0%B8%B7%E0%B8%AD%E0%B8%81%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e17\u0e33\u0e44\u0e21\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e17\u0e33\u0e44\u0e21\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%AA%E0%B8%A1%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%9C%E0%B8%A5%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%94%E0%B8%B5%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%94%E0%B9%89%E0%B8%A7%E0%B8%A2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\" title=\"\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%94%E0%B8%B5%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%94%E0%B9%89%E0%B8%A7%E0%B8%A2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99-2\" title=\"\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\">\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B8%AA%E0%B8%B4%E0%B9%88%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B9%80%E0%B8%AA%E0%B8%B7%E0%B9%89%E0%B8%AD%E0%B8%9C%E0%B9%89%E0%B8%B2%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B9%81%E0%B8%95%E0%B9%88%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A2\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%82%E0%B8%A7%E0%B8%B1%E0%B8%8D%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%AA%E0%B8%B4%E0%B8%99%E0%B8%84%E0%B9%89%E0%B8%B2%E0%B8%9E%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%A1%E0%B8%B5%E0%B8%A2%E0%B8%A1\" title=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>\u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 , \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<strong><span><a onclick=\"read_toggle(1786692785, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1786692785\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1786692785\" style=\"display: none;\"><\/strong> \u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e23\u0e38\u0e48\u0e19 Arena A1522 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d Epson I3200-A1 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e16\u0e36\u0e07 320 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c 1 PASS \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01 \u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07 \u0e25\u0e49\u0e2d\u0e22\u0e32\u0e07\u0e19\u0e33\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e16\u0e34\u0e15\u0e22\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e19\u0e39\u0e19\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<strong><\/div><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%97%E0%B8%84%E0%B9%82%E0%B8%99%E0%B9%82%E0%B8%A5%E0%B8%A2%E0%B8%B5%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%84%E0%B8%B7%E0%B8%AD%E0%B8%AD%E0%B8%B0%E0%B9%84%E0%B8%A3\"><\/span>\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19<a href=\"https:\/\/mimaki-inksub.com\/en\/product\/heatroller190cm\/\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19<\/a> \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e16\u0e48\u0e32\u0e19\u0e40\u0e17\u0e2b\u0e21\u0e36\u0e01 \u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49 \u0e40\u0e01\u0e34\u0e14\u0e25\u0e32\u0e22 \u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%81%E0%B8%A3%E0%B8%B0%E0%B8%9A%E0%B8%A7%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d \u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23, \u0e2b\u0e21\u0e36\u0e01\u0e08\u0e30\u0e16\u0e39\u0e01\u0e2a\u0e31\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e39\u0e07. \u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e35\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e4a\u0e32\u0e0b \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e14\u0e39\u0e14\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e1c\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%97%E0%B8%B3%E0%B9%84%E0%B8%A1%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%95%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%A5%E0%B8%B7%E0%B8%AD%E0%B8%81%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e17\u0e33\u0e44\u0e21\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%84%E0%B8%B8%E0%B8%93%E0%B8%AA%E0%B8%A1%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07, \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e19\u0e17\u0e32\u0e19, \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%9C%E0%B8%A5%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e0a\u0e48\u0e19 <a href=\"https:\/\/virgo-sport.com\/shop\/virgo-sport\/default.aspx?page=pages&amp;url=virgo-sport&amp;pgid=1263&amp;lang=TH\">\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e35\u0e2c\u0e32<\/a> \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e1a\u0e2d\u0e25 \u0e1c\u0e49\u0e32\u0e1a\u0e31\u0e1f\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 <strong><span><a onclick=\"read_toggle(1452232042, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1452232042\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1452232042\" style=\"display: none;\">\u00a0<\/strong> \u0e41\u0e01\u0e49\u0e27 \u0e08\u0e32\u0e19 \u0e2b\u0e21\u0e27\u0e01 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e01 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e1c\u0e49\u0e32\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32 TK, TC, Polyester \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32 Cotton100% \u0e44\u0e14\u0e49<strong><\/div><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%94%E0%B8%B5%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%94%E0%B9%89%E0%B8%A7%E0%B8%A2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99\"><\/span>\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\u0e44\u0e14\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<\/li>\n<li>\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1c\u0e49\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e0b\u0e31\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e01\u0e16\u0e49\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32 Polyester \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e14 \u0e41\u0e25\u0e30 \u0e41\u0e2b\u0e49\u0e07\u0e40\u0e23\u0e47\u0e27<\/li>\n<li>\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e2a\u0e48\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e40\u0e2b\u0e07\u0e37\u0e48\u0e2d \u0e44\u0e21\u0e48\u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22<\/li>\n<li>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/li>\n<li>\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e48\u0e33 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1c\u0e25\u0e07\u0e32\u0e19<\/li>\n<li>\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e09\u0e14\u0e2a\u0e35 \u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%94%E0%B8%B5%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99%E0%B8%94%E0%B9%89%E0%B8%A7%E0%B8%A2%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%A1%E0%B8%8A%E0%B8%B1%E0%B9%88%E0%B8%99-2\"><\/span>\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B8%AA%E0%B8%B4%E0%B9%88%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e35\u0e2c\u0e32 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e41\u0e1c\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e32\u0e2a\u0e4c\u00a0<strong><span><a onclick=\"read_toggle(1041866150, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1041866150\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1041866150\" style=\"display: none;\">\u00a0<\/strong> \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49<strong><\/div><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B9%80%E0%B8%AA%E0%B8%B7%E0%B9%89%E0%B8%AD%E0%B8%9C%E0%B9%89%E0%B8%B2%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B9%81%E0%B8%95%E0%B9%88%E0%B8%87%E0%B8%81%E0%B8%B2%E0%B8%A2\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e1a\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 <strong><span><a onclick=\"read_toggle(1425435753, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink1425435753\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read1425435753\" style=\"display: none;\"><\/strong>\u0e1c\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<strong><\/div><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%84%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%9E%E0%B8%B4%E0%B8%A1%E0%B8%9E%E0%B9%8C%E0%B8%8B%E0%B8%B1%E0%B8%9A%E0%B9%83%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%95%E0%B8%AA%E0%B8%B2%E0%B8%AB%E0%B8%81%E0%B8%A3%E0%B8%A3%E0%B8%A1%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%82%E0%B8%A7%E0%B8%B1%E0%B8%8D%E0%B9%81%E0%B8%A5%E0%B8%B0%E0%B8%AA%E0%B8%B4%E0%B8%99%E0%B8%84%E0%B9%89%E0%B8%B2%E0%B8%9E%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%A1%E0%B8%B5%E0%B8%A2%E0%B8%A1\"><\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 <strong><span><a onclick=\"read_toggle(561476345, '\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d', '\u0e22\u0e48\u0e2d\u0e25\u0e07'); return false;\" class=\"read-link\" id=\"readlink561476345\" style=\"readlink\" href=\"#\">\u0e2d\u0e48\u0e32\u0e19\u0e15\u0e48\u0e2d<\/a><\/span>\n<div class=\"read_div\" id=\"read561476345\" style=\"display: none;\"><\/strong>\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e25\u0e07\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<strong><\/div><\/strong><\/p>\n\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9589\" class=\"elementor elementor-9589\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e384eb3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e384eb3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e7e40f\" data-id=\"0e7e40f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0155e9 elementor-widget elementor-widget-heading\" data-id=\"a0155e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec38dc8 elementor-widget elementor-widget-image\" data-id=\"ec38dc8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" \/><noscript><img decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2dd255 elementor-widget elementor-widget-text-editor\" data-id=\"e2dd255\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 , \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e23\u0e38\u0e48\u0e19 Arena A1522 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d Epson I3200-A1 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e16\u0e36\u0e07 320 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c 1 PASS \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01 \u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07 \u0e25\u0e49\u0e2d\u0e22\u0e32\u0e07\u0e19\u0e33\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e16\u0e34\u0e15\u0e22\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e19\u0e39\u0e19\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae2ea6 elementor-widget elementor-widget-heading\" data-id=\"3ae2ea6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b61ea2d elementor-widget elementor-widget-text-editor\" data-id=\"b61ea2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e16\u0e48\u0e32\u0e19\u0e40\u0e17\u0e2b\u0e21\u0e36\u0e01 \u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaa2764 elementor-widget elementor-widget-heading\" data-id=\"aaa2764\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d3147 elementor-widget elementor-widget-text-editor\" data-id=\"24d3147\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e21\u0e37\u0e48\u0e2d \u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23, \u0e2b\u0e21\u0e36\u0e01\u0e08\u0e30\u0e16\u0e39\u0e01\u0e2a\u0e31\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e39\u0e07. \u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e35\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e4a\u0e32\u0e0b \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e14\u0e39\u0e14\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e1c\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f1f2c elementor-widget elementor-widget-heading\" data-id=\"e8f1f2c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e33\u0e44\u0e21\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5f3023 elementor-widget elementor-widget-text-editor\" data-id=\"d5f3023\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dca749c elementor-widget elementor-widget-heading\" data-id=\"dca749c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0927980 elementor-widget elementor-widget-text-editor\" data-id=\"0927980\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a \u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07, \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e19\u0e17\u0e32\u0e19, \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e46.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9033b88 elementor-widget elementor-widget-heading\" data-id=\"9033b88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7fa86b elementor-widget elementor-widget-text-editor\" data-id=\"c7fa86b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19 \u0e1c\u0e49\u0e32\u0e1a\u0e31\u0e1f\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e01\u0e49\u0e27 \u0e08\u0e32\u0e19 \u0e2b\u0e21\u0e27\u0e01 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e01 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e1c\u0e49\u0e32\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32 TK, TC, Polyester \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e25\u0e07\u0e1a\u0e19\u0e1c\u0e49\u0e32 Cotton100% \u0e44\u0e14\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5f54d elementor-widget elementor-widget-heading\" data-id=\"3d5f54d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-542e235 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"542e235\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e44\u0e14\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1c\u0e49\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e0b\u0e31\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e35\u0e44\u0e21\u0e48\u0e15\u0e01\u0e16\u0e49\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32 Polyester \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e14 \u0e41\u0e25\u0e30 \u0e41\u0e2b\u0e49\u0e07\u0e40\u0e23\u0e47\u0e27<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e0b\u0e31\u0e1a \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e2a\u0e48\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e40\u0e2b\u0e07\u0e37\u0e48\u0e2d \u0e44\u0e21\u0e48\u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e48\u0e33 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14 \u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1c\u0e25\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e09\u0e14\u0e2a\u0e35 \u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d31a437 elementor-widget elementor-widget-heading\" data-id=\"d31a437\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dabc61 elementor-widget elementor-widget-heading\" data-id=\"8dabc61\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99b8b18 elementor-widget elementor-widget-text-editor\" data-id=\"99b8b18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e35\u0e2c\u0e32 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e41\u0e1c\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e32\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1b78b elementor-widget elementor-widget-heading\" data-id=\"4a1b78b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-440f2d2 elementor-widget elementor-widget-text-editor\" data-id=\"440f2d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e25\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e1a\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e1c\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffd39de elementor-widget elementor-widget-heading\" data-id=\"ffd39de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b231b4 elementor-widget elementor-widget-text-editor\" data-id=\"1b231b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e25\u0e07\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-08505d2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"08505d2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cee0624\" data-id=\"cee0624\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc5adef elementor-widget elementor-widget-heading\" data-id=\"bc5adef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29<br>\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 0.89%<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 1 \u0e1b\u0e35<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-199546d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"199546d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-193ed37\" data-id=\"193ed37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a389b7 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2a389b7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e19\u0e43\u0e08\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-853724b\" data-id=\"853724b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cd1672 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3cd1672\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-49244be\" data-id=\"49244be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7460bac elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"7460bac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-074773d\" data-id=\"074773d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-53465a4 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"53465a4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61a7b06\" data-id=\"61a7b06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6076cca elementor-widget elementor-widget-heading\" data-id=\"6076cca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e23\u0e35\u0e27\u0e34\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0e4de61 elementor-hidden-mobile\" data-id=\"0e4de61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bf752da\" data-id=\"bf752da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-398d1f1 elementor-section-content-middle elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"398d1f1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ae455e5\" data-id=\"ae455e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0271e12 elementor-widget elementor-widget-heading\" data-id=\"0271e12\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08cb494 elementor-hidden-mobile\" data-id=\"08cb494\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b099e8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b099e8d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f61c695\" data-id=\"f61c695\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1e1d64 elementor-widget elementor-widget-image\" data-id=\"e1e1d64\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522.png\" class=\"attachment-full size-full wp-image-9653 lazyload\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 36\u0e07\u0e27\u0e14 A1522\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-100x100.png 100w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><noscript><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522.png\" class=\"attachment-full size-full wp-image-9653\" alt=\"\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 36\u0e07\u0e27\u0e14 A1522\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522.png 1000w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-300x300.png 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-150x150.png 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-768x768.png 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-600x600.png 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/\u0e1c\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e1436-\u0e07\u0e27\u0e14-a1522-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8a64246 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a64246\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8407448\" data-id=\"8407448\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ad32e2 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-calculated-fields-form\" data-id=\"9ad32e2\" data-element_type=\"widget\" data-widget_type=\"calculated-fields-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>#fbuilder .cff-button-field{text-align:center;}\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"?\" method=\"post\" enctype=\"multipart\/form-data\" class=\"cff-form \"  dir=\"ltr\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/><pre style=\"display:none !important;\"><script type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname13\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fcurrency\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e32\\u0e04\\u0e32\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":false,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"currencySymbol\":\"\",\"currencyText\":\" \\u0e1a\\u0e32\\u0e17\",\"thousandSeparator\":\",\",\"centSeparator\":\".\",\"noCents\":true,\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":true,\"twoDecimals\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname18\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c %\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 30%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 35%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 40%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 45%\",\"\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c 50%\"],\"optgroup\":[false,false,false,false,false],\"choicesVal\":[\"0.30\",\"0.35\",\"0.40\",\"0.45\",\"0.50\"],\"choicesDep\":[[],[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname11\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e01\\u0e39\\u0e49\",\"size\":\"medium\",\"required\":false,\"exclude\":false,\"toSubmit\":\"value\",\"merge\":0,\"choiceSelected\":\"First Choice - First Choice\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 12 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 24 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e19\\u0e32\\u0e19 36 \\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"12 \",\"24 \",\"36 \"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname14\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fButton\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"sType\":\"calculate\",\"sValue\":\"\\u0e04\\u0e33\\u0e19\\u0e27\\u0e19\\u0e2a\\u0e34\\u0e19\\u0e40\\u0e0a\\u0e37\\u0e48\\u0e2d\",\"sOnclick\":\"\",\"sOnmousedown\":\"\",\"sLoading\":true,\"sMultipage\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname19\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e14\\u0e32\\u0e27\\u0e19\\u0e4c\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname13*fieldname18)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname16\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"prec(fieldname13-fieldname19)\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fnumber\",\"userhelp\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 0.89% \\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 %\",\"predefined\":\"0.89%\",\"predefinedClick\":true,\"required\":false,\"exclude\":false,\"readonly\":true,\"numberpad\":false,\"spinner\":false,\"size\":\"large\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"step\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e22\\u0e2d\\u0e14\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e40\\u0e14\\u0e37\\u0e2d\\u0e19\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"large\",\"eq\":\"PREC(fieldname17\\\/fieldname11)\",\"min\":\"\",\"max\":\"\",\"suffix\":\" \\u0e1a\\u0e32\\u0e17\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":false,\"dformat\":\"number\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname17\",\"shortlabel\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"index\":8,\"ftype\":\"fCalculated\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22+\\u0e22\\u0e2d\\u0e14\\u0e08\\u0e31\\u0e14\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"medium\",\"eq\":\"PREC(fieldname16*0.0089)*(fieldname11)+fieldname16\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\",\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"dynamicEval\":true,\"hidefield\":true,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"\",\"description\":\"\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_13\",\"evalequations\":0,\"evalequations_delay\":0,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"animation_effect\":\"fade\",\"customstyles\":\"#fbuilder .cff-button-field{text-align:center;}\\n#fbuilder .section_breaks label{display:block;text-align:left;font-size:2em !important;margin:20px 0 !important;border-bottom:1px solid #ccc;}\\n\",\"direction\":\"ltr\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n<div class=\"clearer\"><\/div>\n<\/form>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-86db93e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86db93e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c873ed4\" data-id=\"c873ed4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa6399c elementor-widget elementor-widget-image\" data-id=\"aa6399c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"940\" height=\"705\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069 lazyload\" alt=\"\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" data-sizes=\"(max-width: 940px) 100vw, 940px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 940px; --smush-placeholder-aspect-ratio: 940\/705;\" \/><noscript><img decoding=\"async\" width=\"940\" height=\"705\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg\" class=\"attachment-large size-large wp-image-9069\" alt=\"\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150.jpg 940w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-300x225.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-768x576.jpg 768w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/429150-600x450.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0b98acd\" data-id=\"0b98acd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cf5a07 elementor-widget elementor-widget-heading\" data-id=\"9cf5a07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19 INKSUB<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc311f elementor-widget elementor-widget-text-editor\" data-id=\"6cc311f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 INKSUB \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e2d\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19 Printer Sublimation \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8c35f98 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c35f98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23ed671\" data-id=\"23ed671\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6404bd9 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6404bd9\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"kad-wp-gallery65\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-6 rowtight\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-300x300.jpg\" width=\"300\" height=\"300\" alt=\"inksub \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7004-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7023-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7125-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7172-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7083-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_6978-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7054-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7072-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7069-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7061-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7211-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" data-srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 Inksub\" srcset=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-300x300.jpg 300w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-150x150.jpg 150w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-100x100.jpg 100w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-600x600.jpg 600w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-800x800.jpg 800w, https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/IMG_7151-scaled-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"light-dropshaddow\"\/><\/noscript><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b0d8af6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0d8af6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c10451\" data-id=\"5c10451\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd2b86a elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"bd2b86a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347224-1536x1152.jpg\" alt=\"mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347226-1536x1152.jpg\" alt=\"\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347229-1536x1152.jpg\" alt=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/S__31432727.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2a\u0e34\u0e49\u0e2d Mimaki TS100\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/06\/S__23347230-1536x1152.jpg\" alt=\"\u0e02\u0e19\u0e2a\u0e48\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879775.jpg\" alt=\"Mimaki printer \u0e2a\u0e2d\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879771.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23879770.jpg\" alt=\"\u0e25\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Mimaki printer\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846928.jpg\" alt=\"\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/S__23846925.jpg\" alt=\"\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Mimaki ts100-1600\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-786a893\" data-id=\"786a893\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725c976 elementor-widget elementor-widget-heading\" data-id=\"725c976\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b431f0 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8b431f0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5aaad94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5aaad94\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-066b35a\" data-id=\"066b35a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2713b0f elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2713b0f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0948752323\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c64871c\" data-id=\"c64871c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b07900a elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"b07900a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/line.me\/ti\/p\/~@inksubshop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e23\u0e35 @line \u0e40\u0e25\u0e22<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"9373\"]\n","protected":false},"featured_media":9650,"template":"","meta":{"kt_blocks_editor_width":""},"product_cat":[121],"product_tag":[138,136,141,137,143,142,139,140],"class_list":{"0":"post-10051","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-121","7":"product_tag-138","8":"product_tag-136","9":"product_tag-141","10":"product_tag-137","11":"product_tag-143","12":"product_tag-142","13":"product_tag-139","14":"product_tag-140","16":"first","17":"instock","18":"shipping-taxable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 - Mimaki Thailand<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimaki Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-22T03:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 - Mimaki Thailand\",\"isPartOf\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg\",\"datePublished\":\"2023-07-04T04:20:00+00:00\",\"dateModified\":\"2023-09-22T03:08:39+00:00\",\"description\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\",\"breadcrumb\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena a1522\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\",\"item\":\"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#website\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"name\":\"Mimaki Thailand\",\"description\":\"High premium quality\",\"publisher\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#organization\",\"name\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":900,\"height\":260,\"caption\":\"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation\"},\"image\":{\"@id\":\"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\" \/>\n<meta property=\"product:price:amount\" content=\"0\" \/>\n<meta property=\"product:price:currency\" content=\"THB\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 - Mimaki Thailand","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522","og_description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a","og_url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/","og_site_name":"Mimaki Thailand","article_modified_time":"2023-09-22T03:08:39+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/","url":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 - Mimaki Thailand","isPartOf":{"@id":"https:\/\/mimaki-inksub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg","datePublished":"2023-07-04T04:20:00+00:00","dateModified":"2023-09-22T03:08:39+00:00","description":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07320\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e21\u0e36\u0e01\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 3 \u0e25\u0e34\u0e15\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a","breadcrumb":{"@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#primaryimage","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2023\/06\/a1522.jpg","width":1000,"height":1000,"caption":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena a1522"},{"@type":"BreadcrumbList","@id":"https:\/\/mimaki-inksub.com\/en\/product\/printer-arena-a1522-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimaki-inksub.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mimaki-inksub.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a","item":"https:\/\/mimaki-inksub.com\/en\/product-tag\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b8%8b%e0%b8%b1%e0%b8%9a\/"},{"@type":"ListItem","position":4,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Arena A1522"}]},{"@type":"WebSite","@id":"https:\/\/mimaki-inksub.com\/en\/#website","url":"https:\/\/mimaki-inksub.com\/en\/","name":"Mimaki Thailand","description":"High premium quality","publisher":{"@id":"https:\/\/mimaki-inksub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimaki-inksub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimaki-inksub.com\/en\/#organization","name":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation","url":"https:\/\/mimaki-inksub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/mimaki-inksub.com\/en\/wp-content\/uploads\/2022\/05\/logo.png","width":900,"height":260,"caption":"MIMAKI-INKSUB \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 Dye Sublimation"},"image":{"@id":"https:\/\/mimaki-inksub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCRWCBbplSjtm6g97sna0HBA"]}]},"product_brand":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19","product_price_currency":"THB","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/10051"}],"collection":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/10051\/revisions"}],"predecessor-version":[{"id":10054,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product\/10051\/revisions\/10054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media\/9650"}],"wp:attachment":[{"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/media?parent=10051"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_cat?post=10051"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mimaki-inksub.com\/en\/wp-json\/wp\/v2\/product_tag?post=10051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}